﻿{"id":103876,"date":"2018-09-24T06:05:38","date_gmt":"2018-09-24T09:05:38","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=103876"},"modified":"2018-09-23T22:07:52","modified_gmt":"2018-09-24T01:07:52","slug":"o-martirio-como-carrasco-da-pura-alegria","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/","title":{"rendered":"O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA"},"content":{"rendered":"<div class=\"fsc_text\"><p>Desde 2006, a sempre alegre sambista e cantora Beth Carvalho, hoje em 2018, com 72 anos, padece de fortes dores que se irradiam a partir de uma inflama\u00e7\u00e3o na base da coluna &#8211; regi\u00e3o do sacro -, que a obrigam a passar a maior parte do tempo deitada na cama. Chegou a se mudar algumas vezes com mala e cavaquinho para o Pr\u00f3-Card\u00edaco, cuja maior temporada durou 18 anos na mais longa das crises, al\u00e9m de um m\u00eas em coma.<br \/>\nQuando cruciais dores se avizinham, \u00e9 de bom-tom que ela se dirija a seu hospital porque s\u00f3 antibi\u00f3tico na veia resolve. Dos muitos rem\u00e9dios que toma para aliviar a dor, nem mesmo o que custa 5 mil d\u00f3lares por m\u00eas o efeito \u00e9 t\u00e3o eficaz quanto o causado pelo amor \u00e0 vida, \u00e0 m\u00fasica, ao dedilhar um viol\u00e3o, cantando e compondo, ainda que em ambiente que exija sil\u00eancio.<br \/>\nJ\u00e1 comemorou um anivers\u00e1rio no hospital quando promoveu uma feijoada com os convidados levando cerveja. Sempre gozou da fama de beber, tamb\u00e9m pudera, andando com sambistas pra cima e pra baixo. Mas foi a nicotina, desde os 13 anos, que provocou um edema nas cordas vocais e a for\u00e7ou a abandonar o v\u00edcio de fumar h\u00e1 mais de 30 anos. Sen\u00e3o, inabilitada para cantar, a senten\u00e7a de morte.<br \/>\nVive mais tempo com a dor do que sem. Chega a ter um m\u00e9dico especialista em dor. Precisa de tr\u00eas enfermeiras e de home care, um pequeno hospital em casa. Embora confesse que \u201ctem horas que d\u00e1 um desespero e n\u00e3o aguenta mais!\u201d.<br \/>\nNo entanto, n\u00e3o se cansou de sua vida intensa, seja musical, afetiva, familiar e pol\u00edtica, em especial, a rela\u00e7\u00e3o com compositores. N\u00e3o parou de sonhar com projetos como o Instituto do Samba Beth Carvalho. Adora cantar, fazer shows, tanto que pensa em organizar um especial deitada numa chaise longue, pois em p\u00e9 n\u00e3o \u00e9 mais poss\u00edvel. Sentada, desconhece at\u00e9 onde pode ir. Seria a \u00fanica no mundo a se apresentar no palco numa cama &#8211; a Bethm\u00f3vel.<br \/>\nA despeito de sua alma arrebatada pela inspira\u00e7\u00e3o, entusiasmo e paix\u00e3o, n\u00e3o s\u00e3o poucas vezes que Beth Carvalho ouve rumores de que morreu devido ao seu grave estado de sa\u00fade ao longo de 12 anos. Como conviver com o an\u00fancio de sua pr\u00f3pria morte se repetir indefinidamente, sem que Beth possa sequer se livrar da constante submiss\u00e3o ao leito? A evoca\u00e7\u00e3o de \u201cVou festejar\u201d cedeu lugar ao mart\u00edrio em guerra sem tr\u00e9gua com os seus mais vibrantes sucessos, ainda na ordem do dia de Beth Carvalho.<br \/>\nDeus misericordioso, qual \u00e9 o seu carma? Quem sou eu para ir em seu socorro e bradar que ela n\u00e3o merece? Se eu pudesse, a seguraria no colo e a ninava, cantarolando \u201c\u00f4, coisinha t\u00e3o bonitinha do pai\u201d. Para facilitar seu tr\u00e2nsito na Terra e amenizar seu sofrimento.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Desde 2006, a sempre alegre sambista e cantora Beth Carvalho, hoje em 2018, com 72 anos, padece de fortes dores que se irradiam a partir de uma inflama\u00e7\u00e3o na base da coluna &#8211; regi\u00e3o do sacro -, que a obrigam a passar a maior parte do tempo deitada na cama. Chegou a se mudar algumas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[20,29],"tags":[1109,1111,1110,1113,1112],"class_list":["post-103876","post","type-post","status-publish","format-standard","hentry","category-cronicas","category-espiritualidade-cronica","tag-beth","tag-cantora","tag-carvalho","tag-cerveja","tag-violao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Desde 2006, a sempre alegre sambista e cantora Beth Carvalho, hoje em 2018, com 72 anos, padece de fortes dores que se irradiam a partir de uma inflama\u00e7\u00e3o na base da coluna &#8211; regi\u00e3o do sacro -, que a obrigam a passar a maior parte do tempo deitada na cama. Chegou a se mudar algumas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-24T09:05:38+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/","og_locale":"pt_BR","og_type":"article","og_title":"O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA - Jornal DuGAIO","og_description":"Desde 2006, a sempre alegre sambista e cantora Beth Carvalho, hoje em 2018, com 72 anos, padece de fortes dores que se irradiam a partir de uma inflama\u00e7\u00e3o na base da coluna &#8211; regi\u00e3o do sacro -, que a obrigam a passar a maior parte do tempo deitada na cama. Chegou a se mudar algumas [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2018-09-24T09:05:38+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA","datePublished":"2018-09-24T09:05:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/"},"wordCount":507,"commentCount":0,"keywords":["Beth","cantora","Carvalho","cerveja","viol\u00e3o"],"articleSection":["Cr\u00f4nicas","Espiritualidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/","name":"O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2018-09-24T09:05:38+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-martirio-como-carrasco-da-pura-alegria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"O MART\u00cdRIO COMO CARRASCO DA PURA ALEGRIA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/103876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=103876"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/103876\/revisions"}],"predecessor-version":[{"id":103877,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/103876\/revisions\/103877"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=103876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=103876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=103876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}