﻿{"id":104460,"date":"2019-05-13T10:08:08","date_gmt":"2019-05-13T13:08:08","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=104460"},"modified":"2019-05-15T10:11:28","modified_gmt":"2019-05-15T13:11:28","slug":"transitoriedade","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/","title":{"rendered":"TRANSITORIEDADE"},"content":{"rendered":"<div class=\"fsc_text\"><p>Estou exatamente onde deveria estar<br \/>\nA transitoriedade \u00e9 o meu lugar<br \/>\nSe antes me apegava aos medos<br \/>\nHoje o desapego \u00e9 o meu enredo<br \/>\nMinha riqueza<br \/>\nQuanto mais assumo minhas fraquezas<br \/>\nVou construindo minha fortaleza<br \/>\nQue n\u00e3o \u00e9 de pedra e cimento<br \/>\nMas de \u00e1gua, sentimentos<br \/>\nL\u00e1grima que chora<br \/>\nE em outras horas evapora<br \/>\nNoutras vezes tudo molha<br \/>\nE lava<br \/>\nEu n\u00e3o sou o que esperam de mim<br \/>\nNem o que eu mesma esperava<br \/>\nSou muito mais do que isso<br \/>\nE n\u00e3o tenho compromisso com ningu\u00e9m<br \/>\nAl\u00e9m de mim<br \/>\nAm\u00e9m<br \/>\nDigo sim<br \/>\nAo meu destino<br \/>\nAos meus desatinos<br \/>\nE aprendizados<br \/>\nE se algo em mim<br \/>\nJ\u00e1 foi errado<br \/>\nFoi desistir, reclamar<br \/>\nE n\u00e3o saber agradecer<br \/>\nTodo mundo \u00e9 o que deveria ser<br \/>\nCada um de um jeito<br \/>\nE nada \u00e9 defeito<br \/>\nSomos todos imperfeitos<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Estou exatamente onde deveria estar A transitoriedade \u00e9 o meu lugar Se antes me apegava aos medos Hoje o desapego \u00e9 o meu enredo Minha riqueza Quanto mais assumo minhas fraquezas Vou construindo minha fortaleza Que n\u00e3o \u00e9 de pedra e cimento Mas de \u00e1gua, sentimentos L\u00e1grima que chora E em outras horas evapora Noutras [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[50,56],"tags":[],"class_list":["post-104460","post","type-post","status-publish","format-standard","hentry","category-colaboradores","category-tudo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRANSITORIEDADE - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRANSITORIEDADE - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Estou exatamente onde deveria estar A transitoriedade \u00e9 o meu lugar Se antes me apegava aos medos Hoje o desapego \u00e9 o meu enredo Minha riqueza Quanto mais assumo minhas fraquezas Vou construindo minha fortaleza Que n\u00e3o \u00e9 de pedra e cimento Mas de \u00e1gua, sentimentos L\u00e1grima que chora E em outras horas evapora Noutras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-13T13:08:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T13:11:28+00:00\" \/>\n<meta name=\"author\" content=\"Mariana Valle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Valle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRANSITORIEDADE - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/","og_locale":"pt_BR","og_type":"article","og_title":"TRANSITORIEDADE - Jornal DuGAIO","og_description":"Estou exatamente onde deveria estar A transitoriedade \u00e9 o meu lugar Se antes me apegava aos medos Hoje o desapego \u00e9 o meu enredo Minha riqueza Quanto mais assumo minhas fraquezas Vou construindo minha fortaleza Que n\u00e3o \u00e9 de pedra e cimento Mas de \u00e1gua, sentimentos L\u00e1grima que chora E em outras horas evapora Noutras [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2019-05-13T13:08:08+00:00","article_modified_time":"2019-05-15T13:11:28+00:00","author":"Mariana Valle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Valle","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/"},"author":{"name":"Mariana Valle","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"headline":"TRANSITORIEDADE","datePublished":"2019-05-13T13:08:08+00:00","dateModified":"2019-05-15T13:11:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/"},"wordCount":138,"commentCount":0,"articleSection":["Colaboradores","Tudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/","name":"TRANSITORIEDADE - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2019-05-13T13:08:08+00:00","dateModified":"2019-05-15T13:11:28+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/transitoriedade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"TRANSITORIEDADE"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8","name":"Mariana Valle","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","caption":"Mariana Valle"},"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/mvalle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=104460"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104460\/revisions"}],"predecessor-version":[{"id":104461,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104460\/revisions\/104461"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=104460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=104460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=104460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}