﻿{"id":104617,"date":"2019-07-13T20:43:08","date_gmt":"2019-07-13T23:43:08","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=104617"},"modified":"2019-07-14T20:44:22","modified_gmt":"2019-07-14T23:44:22","slug":"se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/","title":{"rendered":"SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR?"},"content":{"rendered":"<div class=\"fsc_text\"><p>Bolsonaro est\u00e1 acostumado a produzir crises para desviar o foco de seu governo &#8211; lembram-se de criar uma Canc\u00fan ao lado da usina at\u00f4mica em Angra? Era preciso abafar os vazamentos de conversa\u00e7\u00f5es criminosas entre Moro, Dallagnol e os desembargadores da 2\u00aa inst\u00e2ncia para manter Lula preso, al\u00e9m dos preju\u00edzos gerados \u00e0 popula\u00e7\u00e3o na vota\u00e7\u00e3o da reforma da Previd\u00eancia, exclu\u00edda a classe pol\u00edtica e os militares. Portanto, nomear o filho 03 para ser o embaixador do Brasil no pa\u00eds mais importante do planeta faz parte da estrat\u00e9gia diab\u00f3lica. Confundir a opini\u00e3o p\u00fablica, com Eduardo Bolsonaro alardeando como experi\u00eancia j\u00e1 ter fritado hamb\u00farguer nos EUA. Sem medo de cair no rid\u00edculo, nem mesmo junto \u00e0 popula\u00e7\u00e3o que votou na fam\u00edlia Bolsonaro, que ainda se impressiona com suas iniciativas, nem de arranhar a imagem hist\u00f3rica e pragmaticamente constru\u00edda pela diplomacia, desde o Bar\u00e3o do Rio Branco. Dane-se se isso nivela seu governo a ditaduras \u00e1rabes e africanas, ou \u00e0 velha pol\u00edtica. Basta dizer que n\u00e3o \u00e9 bem assim! Ou, ent\u00e3o, mentir, tanto faz se a imagem do Brasil vai ficar abalada pelo simples capricho do pai fazer bilu-bilu no seu filho, cuja fun\u00e7\u00e3o anterior era a de escriv\u00e3o da Pol\u00edcia. Obrigando o Poder Judici\u00e1rio a interditar a indica\u00e7\u00e3o por descarado nepotismo e o Senado a n\u00e3o aprovar seu nome por absoluta desqualifica\u00e7\u00e3o se confrontado a embaixadores de grande experi\u00eancia que por l\u00e1 foram submetidos \u00e0 sabatina. A vota\u00e7\u00e3o ser\u00e1 secreta, Bolsonaro nunca se preocupou em construir uma base parlamentar e os senadores n\u00e3o ir\u00e3o querer se comprometer, ainda mais que Eduardo precisa abrir m\u00e3o da cadeira de deputado federal para se habilitar. Mais uma aventura do desequilibrado do Bolsonaro, que se diverte em brincar de presidente. Pois se Cal\u00edgula nomeou seu cavalo Incitatus como senador romano e pensou em design\u00e1-lo c\u00f4nsul de algum territ\u00f3rio anexado, por que n\u00e3o o filho do asno como embaixador?<\/p>\n<div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Bolsonaro est\u00e1 acostumado a produzir crises para desviar o foco de seu governo &#8211; lembram-se de criar uma Canc\u00fan ao lado da usina at\u00f4mica em Angra? Era preciso abafar os vazamentos de conversa\u00e7\u00f5es criminosas entre Moro, Dallagnol e os desembargadores da 2\u00aa inst\u00e2ncia para manter Lula preso, al\u00e9m dos preju\u00edzos gerados \u00e0 popula\u00e7\u00e3o na vota\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[21,23],"tags":[],"class_list":["post-104617","post","type-post","status-publish","format-standard","hentry","category-croniquetas","category-politica-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR? - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR? - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Bolsonaro est\u00e1 acostumado a produzir crises para desviar o foco de seu governo &#8211; lembram-se de criar uma Canc\u00fan ao lado da usina at\u00f4mica em Angra? Era preciso abafar os vazamentos de conversa\u00e7\u00f5es criminosas entre Moro, Dallagnol e os desembargadores da 2\u00aa inst\u00e2ncia para manter Lula preso, al\u00e9m dos preju\u00edzos gerados \u00e0 popula\u00e7\u00e3o na vota\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-13T23:43:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-14T23:44:22+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR? - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/","og_locale":"pt_BR","og_type":"article","og_title":"SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR? - Jornal DuGAIO","og_description":"Bolsonaro est\u00e1 acostumado a produzir crises para desviar o foco de seu governo &#8211; lembram-se de criar uma Canc\u00fan ao lado da usina at\u00f4mica em Angra? Era preciso abafar os vazamentos de conversa\u00e7\u00f5es criminosas entre Moro, Dallagnol e os desembargadores da 2\u00aa inst\u00e2ncia para manter Lula preso, al\u00e9m dos preju\u00edzos gerados \u00e0 popula\u00e7\u00e3o na vota\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2019-07-13T23:43:08+00:00","article_modified_time":"2019-07-14T23:44:22+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR?","datePublished":"2019-07-13T23:43:08+00:00","dateModified":"2019-07-14T23:44:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/"},"wordCount":367,"commentCount":0,"articleSection":["Croniquetas","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/","name":"SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR? - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2019-07-13T23:43:08+00:00","dateModified":"2019-07-14T23:44:22+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/se-caligula-nomeou-seu-cavalo-como-senador-por-que-nao-o-filho-do-asno-como-embaixador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"SE CAL\u00cdGULA NOMEOU SEU CAVALO COMO SENADOR, POR QUE N\u00c3O O FILHO DO ASNO COMO EMBAIXADOR?"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=104617"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104617\/revisions"}],"predecessor-version":[{"id":104618,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104617\/revisions\/104618"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=104617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=104617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=104617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}