﻿{"id":104626,"date":"2019-07-22T00:02:41","date_gmt":"2019-07-22T03:02:41","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=104626"},"modified":"2019-07-22T20:15:45","modified_gmt":"2019-07-22T23:15:45","slug":"vivendo-e-aprendendo-com-as-perdas","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/","title":{"rendered":"VIVENDO E APRENDENDO COM AS PERDAS"},"content":{"rendered":"<div class=\"fsc_text\"><div>Buscar a realiza\u00e7\u00e3o de seu sonho, trabalhando de sol a sol, \u00e9 importante e o torna mais forte, dando fundamento \u00e0 sua exist\u00eancia ao ensin\u00e1-lo muito &#8211; a escola da vida. Contanto que tenha a humildade de reconhecer que nem sempre poder\u00e1 alcan\u00e7ar exatamente o que deseja. Ao que se lan\u00e7ou ou ambicionou, por maior esfor\u00e7o que tenha dispendido. J\u00e1 que a realidade \u00e9 deveras complexa e as necessidades de todos precisam ser supridas.<\/div>\n<div>Mas o que fazer se a nossa cultura \u00e9 a da supera\u00e7\u00e3o? Ouvimos isso dos pais, dos educadores, dos formadores de opini\u00e3o. Havemos que perseguir essa meta, caso contr\u00e1rio, teremos que decretar a fal\u00eancia moral, sen\u00e3o seremos sentenciados pela turba ignara.<\/div>\n<div>Acontece que paira sobre n\u00f3s uma ordem c\u00f3smica que a tudo preside e, por isso, muitas vezes n\u00e3o conseguimos alcan\u00e7ar as metas que tra\u00e7amos, pois cada passo dado ou interven\u00e7\u00e3o segura no seu destino sempre afetar\u00e1 a vida de outrem. Sobrevindo a frustra\u00e7\u00e3o e a sensa\u00e7\u00e3o de injusti\u00e7a, pois n\u00e3o atinamos que somos partes de um Todo e jamais poder\u00edamos pensar apenas em nossos objetivos pessoais, j\u00e1 que todos os seres humanos t\u00eam os mesmos direitos.<\/div>\n<div>Que tal, no acumular flagrantes fracassos, come\u00e7ar a pensar em aceitar a vida da forma que ela se apresenta? Pode at\u00e9 parecer que estamos fugindo da raia, que nossa atitude denuncia desist\u00eancia, a pura acomoda\u00e7\u00e3o. Mas a aceita\u00e7\u00e3o de uma realidade a qual n\u00e3o nos cabe abalar suas estruturas \u00e9 uma prova de grande sabedoria. Isso n\u00e3o tem como ser ensinado, s\u00f3 se aprende vivendo. N\u00e3o temendo aparentes derrotas, quando lutamos e exigimos levar de vencida nossos contr\u00e1rios.<\/div>\n<div>Vivemos numa sociedade que n\u00e3o se det\u00e9m para pensar, pressionada pelos descontroles a que estamos sujeitos, num constante estado de tens\u00e3o. N\u00e3o conseguimos relaxar, como se pud\u00e9ssemos assumir o controle da Vida e de nossos problemas.<\/div>\n<div>Somos incapazes de nos impregnar de um esp\u00edrito de humildade suficiente para descobrir naquilo que se perde o quanto se pode tamb\u00e9m ganhar. Arrog\u00e2ncia e prepot\u00eancia, filhos leg\u00edtimos de uma vaidade que se julga soberana e que faz de nosso ego o centro do Universo, o que ele nunca ser\u00e1. Precisamos exercitar constantemente a aceita\u00e7\u00e3o do aparente fracasso, uma sabedoria que permite abrir novas oportunidades e arejar a pr\u00f3pria vida.<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Buscar a realiza\u00e7\u00e3o de seu sonho, trabalhando de sol a sol, \u00e9 importante e o torna mais forte, dando fundamento \u00e0 sua exist\u00eancia ao ensin\u00e1-lo muito &#8211; a escola da vida. Contanto que tenha a humildade de reconhecer que nem sempre poder\u00e1 alcan\u00e7ar exatamente o que deseja. Ao que se lan\u00e7ou ou ambicionou, por maior [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[20,29],"tags":[1349,1350],"class_list":["post-104626","post","type-post","status-publish","format-standard","hentry","category-cronicas","category-espiritualidade-cronica","tag-fracasso","tag-tensao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIVENDO E APRENDENDO COM AS PERDAS - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIVENDO E APRENDENDO COM AS PERDAS - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Buscar a realiza\u00e7\u00e3o de seu sonho, trabalhando de sol a sol, \u00e9 importante e o torna mais forte, dando fundamento \u00e0 sua exist\u00eancia ao ensin\u00e1-lo muito &#8211; a escola da vida. Contanto que tenha a humildade de reconhecer que nem sempre poder\u00e1 alcan\u00e7ar exatamente o que deseja. Ao que se lan\u00e7ou ou ambicionou, por maior [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-22T03:02:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-22T23:15:45+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIVENDO E APRENDENDO COM AS PERDAS - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/","og_locale":"pt_BR","og_type":"article","og_title":"VIVENDO E APRENDENDO COM AS PERDAS - Jornal DuGAIO","og_description":"Buscar a realiza\u00e7\u00e3o de seu sonho, trabalhando de sol a sol, \u00e9 importante e o torna mais forte, dando fundamento \u00e0 sua exist\u00eancia ao ensin\u00e1-lo muito &#8211; a escola da vida. Contanto que tenha a humildade de reconhecer que nem sempre poder\u00e1 alcan\u00e7ar exatamente o que deseja. Ao que se lan\u00e7ou ou ambicionou, por maior [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2019-07-22T03:02:41+00:00","article_modified_time":"2019-07-22T23:15:45+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"VIVENDO E APRENDENDO COM AS PERDAS","datePublished":"2019-07-22T03:02:41+00:00","dateModified":"2019-07-22T23:15:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/"},"wordCount":419,"commentCount":0,"keywords":["fracasso","tens\u00e3o"],"articleSection":["Cr\u00f4nicas","Espiritualidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/","name":"VIVENDO E APRENDENDO COM AS PERDAS - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2019-07-22T03:02:41+00:00","dateModified":"2019-07-22T23:15:45+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/vivendo-e-aprendendo-com-as-perdas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"VIVENDO E APRENDENDO COM AS PERDAS"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=104626"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104626\/revisions"}],"predecessor-version":[{"id":104627,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/104626\/revisions\/104627"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=104626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=104626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=104626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}