﻿{"id":106215,"date":"2021-07-19T00:35:00","date_gmt":"2021-07-19T03:35:00","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=106215"},"modified":"2023-05-12T19:25:40","modified_gmt":"2023-05-12T22:25:40","slug":"lgbtqiap","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/","title":{"rendered":"LGBTQIAP+"},"content":{"rendered":"<div class=\"fsc_text\">\n<p>A sigla LGBTQIAP+ designa uma gama de identidades de g\u00eanero e orienta\u00e7\u00f5es sexuais que fogem ao normativo heterossexual e cisg\u00eanero. Cisgeneridade \u00e9 o termo utilizado para se referir ao indiv\u00edduo que se identifica, em todos os aspectos, com o seu g\u00eanero de nascen\u00e7a. Por exemplo, algu\u00e9m que se identifica como mulher e foi designada como mulher ao nascer \u00e9 uma mulher cisg\u00eanera.<br>L de l\u00e9sbica, a orienta\u00e7\u00e3o sexual de mulheres que se relacionam sexual e afetivamente com mulheres. G de gay, a orienta\u00e7\u00e3o sexual de homens com homens. B de bissexual, de pessoas que se relacionam com homens e mulheres.<br>T de travestis e transg\u00eaneros, identidade de g\u00eanero de pessoas que n\u00e3o se identificam com os g\u00eaneros atribu\u00eddos no nascimento com base na genit\u00e1lia. Percep\u00e7\u00e3o clara de que travestis e transg\u00eaneros n\u00e3o encontraram representatividade na homossexualidade, predominante na antiga inscri\u00e7\u00e3o GLS (Gays, L\u00e9sbicas e Simpatizantes).<br>Q de queer, identidade de g\u00eanero de pessoas que n\u00e3o se reconhecem no binarismo homem\/mulher. I de intersexuais, que apresentam varia\u00e7\u00f5es em cromossomos ou \u00f3rg\u00e3os genitais que n\u00e3o se encaixam nas categorias homem e mulher. A de assexual, orienta\u00e7\u00e3o sexual caracterizada pela aus\u00eancia de atra\u00e7\u00e3o sexual por qualquer pessoa. P de pansexual, orienta\u00e7\u00e3o sexual pontuada pela atra\u00e7\u00e3o sexual e\/ou rom\u00e2ntica por qualquer sexo ou identidade de g\u00eanero.<br>GLS virou g\u00eanero de boate. A ampla utiliza\u00e7\u00e3o da sigla se d\u00e1 num contexto din\u00e2mico de reconhecimento de direitos nas d\u00e9cadas de 1990 e 2000, quando se diversifica a compreens\u00e3o dos mais variados g\u00eaneros e sexualidades buscando seus pares e come\u00e7am a ocorrer processos de diferencia\u00e7\u00e3o. Em 2008, a nomenclatura passou de GLBT (Gays, L\u00e9sbicas, Bissexuais e Travestis e Transg\u00eaneros) para LGBT, de modo a dar mais visibilidade \u00e0s l\u00e9sbicas, de conformidade com o padr\u00e3o de v\u00e1rios pa\u00edses. Hoje \u00e9 LGBTQIAP+. A inten\u00e7\u00e3o expressa no sinal + \u00e9 dar conta das experi\u00eancias e viv\u00eancias de mais g\u00eaneros e sexualidades. A exist\u00eancia de cada letra reivindica igualdade de direitos para pessoas que n\u00e3o t\u00eam sua cidadania e, no limite, sua identidade, socialmente reconhecida. Ao mesmo tempo, a adi\u00e7\u00e3o de novas letras reconhece as diferen\u00e7as entre os sujeitos representados e busca uma a\u00e7\u00e3o pol\u00edtica pautada tamb\u00e9m nesta diversidade. N\u00e3o existe um \u00f3rg\u00e3o oficialmente respons\u00e1vel por essas mudan\u00e7as, embora a sigla seja legitimada pela comunidade.<br>Letras mai\u00fasculas de quem n\u00e3o mais aceita ser tratado como min\u00fasculos. Cidadania pura para ser exercida de fato. Pertencimento a um mundo onde o ser humano ter\u00e1 de se transformar para que o afeto encontre novas formas de se expressar.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A sigla LGBTQIAP+ designa uma gama de identidades de g\u00eanero e orienta\u00e7\u00f5es sexuais que fogem ao normativo heterossexual e cisg\u00eanero. Cisgeneridade \u00e9 o termo utilizado para se referir ao indiv\u00edduo que se identifica, em todos os aspectos, com o seu g\u00eanero de nascen\u00e7a. Por exemplo, algu\u00e9m que se identifica como mulher e foi designada como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[31,20],"tags":[],"class_list":["post-106215","post","type-post","status-publish","format-standard","hentry","category-a-critica-da-critica-cronica","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LGBTQIAP+ - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LGBTQIAP+ - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"A sigla LGBTQIAP+ designa uma gama de identidades de g\u00eanero e orienta\u00e7\u00f5es sexuais que fogem ao normativo heterossexual e cisg\u00eanero. Cisgeneridade \u00e9 o termo utilizado para se referir ao indiv\u00edduo que se identifica, em todos os aspectos, com o seu g\u00eanero de nascen\u00e7a. Por exemplo, algu\u00e9m que se identifica como mulher e foi designada como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-19T03:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-12T22:25:40+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LGBTQIAP+ - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/","og_locale":"pt_BR","og_type":"article","og_title":"LGBTQIAP+ - Jornal DuGAIO","og_description":"A sigla LGBTQIAP+ designa uma gama de identidades de g\u00eanero e orienta\u00e7\u00f5es sexuais que fogem ao normativo heterossexual e cisg\u00eanero. Cisgeneridade \u00e9 o termo utilizado para se referir ao indiv\u00edduo que se identifica, em todos os aspectos, com o seu g\u00eanero de nascen\u00e7a. Por exemplo, algu\u00e9m que se identifica como mulher e foi designada como [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2021-07-19T03:35:00+00:00","article_modified_time":"2023-05-12T22:25:40+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"LGBTQIAP+","datePublished":"2021-07-19T03:35:00+00:00","dateModified":"2023-05-12T22:25:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/"},"wordCount":476,"commentCount":0,"articleSection":["A cr\u00edtica da cr\u00edtica","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/","name":"LGBTQIAP+ - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2021-07-19T03:35:00+00:00","dateModified":"2023-05-12T22:25:40+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/lgbtqiap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"LGBTQIAP+"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/106215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=106215"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/106215\/revisions"}],"predecessor-version":[{"id":106216,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/106215\/revisions\/106216"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=106215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=106215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=106215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}