﻿{"id":106382,"date":"2021-09-24T17:03:00","date_gmt":"2021-09-24T20:03:00","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=106382"},"modified":"2023-05-12T18:06:00","modified_gmt":"2023-05-12T21:06:00","slug":"bolsonaro-e-dr-mengele-feitos-um-para-o-outro","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/","title":{"rendered":"BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO"},"content":{"rendered":"<div class=\"fsc_text\">\n<p>Bolsonaro, como presidente, al\u00e9m de ter sido eleito apoiando torturas e execu\u00e7\u00f5es na ditadura militar, personificadas em seu \u00eddolo, Coronel Ustra, durante a pandemia, se igualou ao m\u00e9dico nazista, Dr. Mengele, que realizou experimentos humanos&nbsp;e pesquisas gen\u00e9ticas mort\u00edferas em prisioneiros na 2\u00aa Guerra Mundial. Por meio da Prevent Senior, sob cobertura da pusilanimidade do Conselho Federal de Medicina, impingindo tratamento precoce \u00e0 base de cloroquina, ivermectina, azitromicina e outros medicamentos (kit Covid), adulterando prontu\u00e1rios e certid\u00f5es de \u00f3bitos para esconder mortes pela Covid-19, assim como n\u00e3o informando aos pacientes que rem\u00e9dios estavam tomando. Todo esse aparato voltado para o exterm\u00ednio e justificar a teoria da imunidade de rebanho, de modo a extinguir o v\u00edrus infectando toda a popula\u00e7\u00e3o, propagandeando rem\u00e9dios sabidamente ineficazes contra a doen\u00e7a. Explorando a not\u00f3ria ignor\u00e2ncia do povo brasileiro a respeito das enfermidades que atazanam a Humanidade, apesar do folclore em torno de cada um de n\u00f3s se achar m\u00e9dico e autoridade. Resultado: muitos usados como cobaias humanas em testes remontados ao genoc\u00eddio, apenas para revestir de verniz cient\u00edfico o negacionismo bolsonarista. N\u00e3o se trata somente de charlatanismo, mas de crimes de esp\u00e9cimes da pior qualidade de ser humano do n\u00edvel do Dr. Mengele, que fugiu da Alemanha em 1945 para, em 1979, aos 67 anos, morrer afogado no Brasil, em Bertioga, v\u00edtima de um AVC. A caminho do Inferno, \u00e9 para l\u00e1 que Bolsonaro se juntar\u00e1 a Mengele e Ustra.&nbsp;&nbsp;<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Bolsonaro, como presidente, al\u00e9m de ter sido eleito apoiando torturas e execu\u00e7\u00f5es na ditadura militar, personificadas em seu \u00eddolo, Coronel Ustra, durante a pandemia, se igualou ao m\u00e9dico nazista, Dr. Mengele, que realizou experimentos humanos&nbsp;e pesquisas gen\u00e9ticas mort\u00edferas em prisioneiros na 2\u00aa Guerra Mundial. Por meio da Prevent Senior, sob cobertura da pusilanimidade do Conselho [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[21,23],"tags":[],"class_list":["post-106382","post","type-post","status-publish","format-standard","hentry","category-croniquetas","category-politica-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Bolsonaro, como presidente, al\u00e9m de ter sido eleito apoiando torturas e execu\u00e7\u00f5es na ditadura militar, personificadas em seu \u00eddolo, Coronel Ustra, durante a pandemia, se igualou ao m\u00e9dico nazista, Dr. Mengele, que realizou experimentos humanos&nbsp;e pesquisas gen\u00e9ticas mort\u00edferas em prisioneiros na 2\u00aa Guerra Mundial. Por meio da Prevent Senior, sob cobertura da pusilanimidade do Conselho [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-24T20:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-12T21:06:00+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/","og_locale":"pt_BR","og_type":"article","og_title":"BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO - Jornal DuGAIO","og_description":"Bolsonaro, como presidente, al\u00e9m de ter sido eleito apoiando torturas e execu\u00e7\u00f5es na ditadura militar, personificadas em seu \u00eddolo, Coronel Ustra, durante a pandemia, se igualou ao m\u00e9dico nazista, Dr. Mengele, que realizou experimentos humanos&nbsp;e pesquisas gen\u00e9ticas mort\u00edferas em prisioneiros na 2\u00aa Guerra Mundial. Por meio da Prevent Senior, sob cobertura da pusilanimidade do Conselho [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2021-09-24T20:03:00+00:00","article_modified_time":"2023-05-12T21:06:00+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO","datePublished":"2021-09-24T20:03:00+00:00","dateModified":"2023-05-12T21:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/"},"wordCount":265,"commentCount":0,"articleSection":["Croniquetas","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/","name":"BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2021-09-24T20:03:00+00:00","dateModified":"2023-05-12T21:06:00+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/bolsonaro-e-dr-mengele-feitos-um-para-o-outro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"BOLSONARO E DR. MENGELE, FEITOS UM PARA O OUTRO"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/106382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=106382"}],"version-history":[{"count":2,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/106382\/revisions"}],"predecessor-version":[{"id":106405,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/106382\/revisions\/106405"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=106382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=106382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=106382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}