﻿{"id":109414,"date":"2024-03-20T22:48:18","date_gmt":"2024-03-21T01:48:18","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=109414"},"modified":"2024-03-20T22:50:29","modified_gmt":"2024-03-21T01:50:29","slug":"e-de-proposito-10-fonte-de-renda","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/","title":{"rendered":"\u00c9 DE PROP\u00d3SITO: 10 &#8211; FONTE DE RENDA"},"content":{"rendered":"<div class=\"fsc_text\">\n<p>Preciso que renda<br>a minha fonte de vida.<br>A minha frente,<br>na minha fronte,<br>sem renda,<br>s\u00f3 vida e d\u00edvida,<br>em fonte arial,<br>nessa p\u00e1gina preenchida.<\/p>\n\n\n\n<p>Poesia d\u00e1 renda?<br>N\u00e3o sei, mas \u00e9 transparente.<br>Voc\u00ea n\u00e3o a sente?<br>Minha frente colorida?<br>O verso tamb\u00e9m convida,<br>com vida.<br>Preciso de outra fonte de renda.<br>Preciso que renda<br>a minha fonte de vida.<\/p>\n\n\n\n<p>Escrevi este poema antes de 2012. Ele foi publicado no meu segundo livro, \u201cPuro Instinto\u201d, lan\u00e7ado originalmente com coordena\u00e7\u00e3o editorial do Delmo Fonseca\u2026 Eis uma pessoa que sumiu do meio liter\u00e1rio, infelizmente. Sou muito grata a ele, pois, depois do meu amado mestre Cairo Trindade, que sempre me ensinou e me orientou na literatura, Delmo foi o terceiro a ver potencial comercial em mim como escritora, me convidando e investindo em mim como autora da Editora Sapere. E estava certo. Imprimiu apenas 230 livros para o lan\u00e7amento. Perguntou pra minha m\u00e3e:<br>_ Voc\u00ea n\u00e3o vai comprar o seu?<br>_ Vou deixar pra depois. &#8211; ela respondeu.<br>E sim, ela comprou, mas s\u00f3 depois que eu j\u00e1 tinha vendido toda a primeira tiragem assim, num s\u00f3 primeiro dia.<\/p>\n\n\n\n<p>O primeiro a pagar pelos meus poemas e sempre me incentivar a persistir foi o Ant\u00f4nio Carlos Gaio, que existe em minha vida desde antes de eu nascer, atrav\u00e9s de sua \u00edntima conviv\u00eancia com meus pais.<\/p>\n\n\n\n<p>Ao ler meus poemas pela primeira vez, Gaio me convidou pra degustar deliciosas pizzas na Pizzaria Braz do Jardim Bot\u00e2nico e, num longo e afetuoso papo, me contou de quando ele escrevia junto com meu pai, num jornal, e o quanto ele via em mim e na minha escrita, tra\u00e7os da intelectualidade e eloqu\u00eancia de meu pai casados com a espontaneidade e questionadora alegria do belo vulc\u00e3o que \u00e9 minha m\u00e3e. E foi assim que ele me incentivou a ir al\u00e9m do que estava ali, al\u00e9m do que meus pr\u00f3prios progenitores enxergavam em mim, atrav\u00e9s de uma valoriza\u00e7\u00e3o mensal e sem pre\u00e7o que ele vem me dando financeiramente desde 2008, quando comecei minhas colunas no seu Jornal DuGaio.<\/p>\n\n\n\n<p>Por tantas vezes, para n\u00e3o dizer por toda minha vida at\u00e9 aqui, duvidei de que eu poderia sim me sustentar exercendo meu maior dom e prazer, que \u00e9 escrever. Em todas essas vezes, mesmo sem saber &#8211; ou ser\u00e1 que ele sempre soube? &#8211; Gaio esteve l\u00e1 para me mostrar que meus pais estavam errados em suas cren\u00e7as limitantes, achando que isso era um sonho fora da realidade. O que ele me paga, foi o valor que sustentou a taxa mensal do condom\u00ednio e parte do aluguel do apartamento que dividi com meu marido por 3 anos, antes de eu voltar para a casa da minha m\u00e3e.<\/p>\n\n\n\n<p>Agora estou aqui, no ventre materno que mais uma vez precisa de mim e eu dele. Vim com marido e dois filhos cachorros. E, nestas condi\u00e7\u00f5es, mais uma vez, \u00e9 o justo valor que o Gaio me d\u00e1, que est\u00e1 me ajudando a investir na minha microempresa como Editora Independente. Gra\u00e7as \u00e0 6 consecutivos anos de terapia com a amada Corrita, outro anjo em minha vida, hoje n\u00e3o tenho tantas d\u00favidas. A espiritualidade tamb\u00e9m se abriu em minha vida. O Reiki abriu e harmonizou meus chakras e despertou um caminho sem volta.<\/p>\n\n\n\n<p>Hoje troquei a revolta e o obscurantismo, a falta de autoconsci\u00eancia por presen\u00e7a constante dentro de mim. Consigo me olhar de fora, n\u00e3o mais com olhos de quem n\u00e3o reconhece em mim o que sempre fui, n\u00e3o como quem teme que eu n\u00e3o corresponda \u00e0s cobran\u00e7as do mundo e me humilhe ou me julgue por eu ter mamado tanto tempo nas tetas de quem me pariu. Eu trabalho desde os 19 anos, mas minha m\u00e3e parou de me dar leite antes mesmo de um m\u00eas de vida. Eu nasci de 8 meses e fiquei um bom tempo mamando ar, sem nem minha m\u00e3e saber. Freud explica. Depois eu volto pra este detalhe.<\/p>\n\n\n\n<p>O que quero dizer com este longo relato depois do poema Fonte de Renda, escrito h\u00e1 mais de 10 anos, \u00e9 que hoje minha fonte n\u00e3o secou, pelo contr\u00e1rio. Eu n\u00e3o s\u00f3 preciso como consigo fazer render minha fonte de vida, que \u00e9 escrever. Ainda tenho muita vida para render. Muita rima para vender. Muita cachoeira pra rimar e muitas d\u00edvidas a honrar, mas quitei a principal delas: a antes eterna d\u00edvida comigo mesma. N\u00e3o s\u00f3 quitei. Hoje tenho cr\u00e9dito. Tenho m\u00e9rito. Porque fa\u00e7o o que sempre poderia ter feito e n\u00e3o sabia. O que era f\u00e1cil e eu n\u00e3o via, o que sempre foi para mim magia. Escrever. Esta \u00e9 minha maior alegria.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Preciso que rendaa minha fonte de vida.A minha frente,na minha fronte,sem renda,s\u00f3 vida e d\u00edvida,em fonte arial,nessa p\u00e1gina preenchida. Poesia d\u00e1 renda?N\u00e3o sei, mas \u00e9 transparente.Voc\u00ea n\u00e3o a sente?Minha frente colorida?O verso tamb\u00e9m convida,com vida.Preciso de outra fonte de renda.Preciso que rendaa minha fonte de vida. Escrevi este poema antes de 2012. Ele foi publicado [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[50,56],"tags":[],"class_list":["post-109414","post","type-post","status-publish","format-standard","hentry","category-colaboradores","category-tudo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9 DE PROP\u00d3SITO: 10 - FONTE DE RENDA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9 DE PROP\u00d3SITO: 10 - FONTE DE RENDA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Preciso que rendaa minha fonte de vida.A minha frente,na minha fronte,sem renda,s\u00f3 vida e d\u00edvida,em fonte arial,nessa p\u00e1gina preenchida. Poesia d\u00e1 renda?N\u00e3o sei, mas \u00e9 transparente.Voc\u00ea n\u00e3o a sente?Minha frente colorida?O verso tamb\u00e9m convida,com vida.Preciso de outra fonte de renda.Preciso que rendaa minha fonte de vida. Escrevi este poema antes de 2012. Ele foi publicado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T01:48:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T01:50:29+00:00\" \/>\n<meta name=\"author\" content=\"Mariana Valle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Valle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9 DE PROP\u00d3SITO: 10 - FONTE DE RENDA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00c9 DE PROP\u00d3SITO: 10 - FONTE DE RENDA - Jornal DuGAIO","og_description":"Preciso que rendaa minha fonte de vida.A minha frente,na minha fronte,sem renda,s\u00f3 vida e d\u00edvida,em fonte arial,nessa p\u00e1gina preenchida. Poesia d\u00e1 renda?N\u00e3o sei, mas \u00e9 transparente.Voc\u00ea n\u00e3o a sente?Minha frente colorida?O verso tamb\u00e9m convida,com vida.Preciso de outra fonte de renda.Preciso que rendaa minha fonte de vida. Escrevi este poema antes de 2012. Ele foi publicado [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2024-03-21T01:48:18+00:00","article_modified_time":"2024-03-21T01:50:29+00:00","author":"Mariana Valle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Valle","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/"},"author":{"name":"Mariana Valle","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"headline":"\u00c9 DE PROP\u00d3SITO: 10 &#8211; FONTE DE RENDA","datePublished":"2024-03-21T01:48:18+00:00","dateModified":"2024-03-21T01:50:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/"},"wordCount":810,"commentCount":0,"articleSection":["Colaboradores","Tudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/","name":"\u00c9 DE PROP\u00d3SITO: 10 - FONTE DE RENDA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2024-03-21T01:48:18+00:00","dateModified":"2024-03-21T01:50:29+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-10-fonte-de-renda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"\u00c9 DE PROP\u00d3SITO: 10 &#8211; FONTE DE RENDA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8","name":"Mariana Valle","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","caption":"Mariana Valle"},"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/mvalle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=109414"}],"version-history":[{"count":2,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109414\/revisions"}],"predecessor-version":[{"id":109418,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109414\/revisions\/109418"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=109414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=109414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=109414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}