﻿{"id":109426,"date":"2024-03-25T20:12:34","date_gmt":"2024-03-25T23:12:34","guid":{"rendered":"https:\/\/www.jornaldugaio.com.br\/?p=109426"},"modified":"2024-03-31T17:59:12","modified_gmt":"2024-03-31T20:59:12","slug":"e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/","title":{"rendered":"\u00c9 DE PROP\u00d3SITO: 13 &#8211; JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO"},"content":{"rendered":"<div class=\"fsc_text\">\n<p>J\u00e1 que terminei o cap\u00edtulo anterior falando de luzes \u00e0 minha volta, para os mais c\u00e9ticos, aqueles que s\u00f3 acreditam na ci\u00eancia e acham que espiritualidade \u00e9 coisa de maluco (como se n\u00e3o fosse inclusive estudada e comprovada pela ci\u00eancia hoje), parto para um ponto bem pr\u00e1tico. Fui \u00e0 Neuropsic\u00f3loga antes de ontem. Depois de 1h15 relatando os principais fatos que eu julgava importantes para que ela me conhecesse psicologicamente, ela me deu uma resposta muito interessante:<\/p>\n\n\n\n<p>\u201cSe voc\u00ea quer mesmo fazer o teste de TDAH*, voc\u00ea pode, mas na minha experi\u00eancia de muitos anos trabalhando com isso, por tudo que vi aqui, voc\u00ea n\u00e3o tem nada disso. Voc\u00ea \u00e9 de uma simplicidade emocional muito grande e tem muitos recursos pra conseguir o que quer. A \u00fanica quest\u00e3o \u00e9 que voc\u00ea teve uma vida muito sofrida\u201d.<\/p>\n\n\n\n<p>*No cap\u00edtulo anterior, eu contei que conversei com minha prima, n\u00e9? Mas n\u00e3o contei o que ela me disse sobre TDAH &#8211; Transtorno de D\u00e9ficit de Aten\u00e7\u00e3o e Hiperfoco. Pelos sintomas que ela me descreveu, me identifiquei, resolvi procurar uma Neuropsic\u00f3loga e fazer o teste, para ver se este seria o meu diagn\u00f3stico. Se explicaria tantos anos, desde a adolesc\u00eancia, de tanta dificuldade em persistir no que quero, sem ser derrubada por per\u00edodos depressivos. Por sempre me auto sabotar, procrastinar o que \u00e9 mais importante, por ter tido tantos anos de uma autoestima t\u00e3o baixa.<\/p>\n\n\n\n<p>E aliados a momentos de doen\u00e7a e quase in\u00e9rcia, sempre vinham dias de ins\u00f4nia em que eu me culpava pelos momentos parada e de repente minha mente entrava num verdadeiro looping de autoculpa e autocobran\u00e7a, de mil planos e ideias mil, mas, como eu n\u00e3o conseguia resolver os problemas no tempo que eu julgava necess\u00e1rio, eu acabava entrando de novo na tal depress\u00e3o paralisante. Ficava que nem um ioi\u00f4 entre os dois estados.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 \u00e0 toa que uma pessoa que mal me conhecia, mas na \u00e9poca queria pegar algo que supostamente era meu (ningu\u00e9m tem nada nem ningu\u00e9m, doce ilus\u00e3o), disse pra outro algu\u00e9m que eu era bipolar. Bipolar era sua v\u00f3! Ali\u00e1s, a minha. Mas eu n\u00e3o sou ela. Nem preciso caber no diagn\u00f3stico de ningu\u00e9m que n\u00e3o vai poder me ajudar.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>J\u00e1 que terminei o cap\u00edtulo anterior falando de luzes \u00e0 minha volta, para os mais c\u00e9ticos, aqueles que s\u00f3 acreditam na ci\u00eancia e acham que espiritualidade \u00e9 coisa de maluco (como se n\u00e3o fosse inclusive estudada e comprovada pela ci\u00eancia hoje), parto para um ponto bem pr\u00e1tico. Fui \u00e0 Neuropsic\u00f3loga antes de ontem. Depois de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[50,56],"tags":[],"class_list":["post-109426","post","type-post","status-publish","format-standard","hentry","category-colaboradores","category-tudo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9 DE PROP\u00d3SITO: 13 - JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9 DE PROP\u00d3SITO: 13 - JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"J\u00e1 que terminei o cap\u00edtulo anterior falando de luzes \u00e0 minha volta, para os mais c\u00e9ticos, aqueles que s\u00f3 acreditam na ci\u00eancia e acham que espiritualidade \u00e9 coisa de maluco (como se n\u00e3o fosse inclusive estudada e comprovada pela ci\u00eancia hoje), parto para um ponto bem pr\u00e1tico. Fui \u00e0 Neuropsic\u00f3loga antes de ontem. Depois de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T23:12:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-31T20:59:12+00:00\" \/>\n<meta name=\"author\" content=\"Mariana Valle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Valle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9 DE PROP\u00d3SITO: 13 - JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00c9 DE PROP\u00d3SITO: 13 - JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO - Jornal DuGAIO","og_description":"J\u00e1 que terminei o cap\u00edtulo anterior falando de luzes \u00e0 minha volta, para os mais c\u00e9ticos, aqueles que s\u00f3 acreditam na ci\u00eancia e acham que espiritualidade \u00e9 coisa de maluco (como se n\u00e3o fosse inclusive estudada e comprovada pela ci\u00eancia hoje), parto para um ponto bem pr\u00e1tico. Fui \u00e0 Neuropsic\u00f3loga antes de ontem. Depois de [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2024-03-25T23:12:34+00:00","article_modified_time":"2024-03-31T20:59:12+00:00","author":"Mariana Valle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Valle","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/"},"author":{"name":"Mariana Valle","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"headline":"\u00c9 DE PROP\u00d3SITO: 13 &#8211; JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO","datePublished":"2024-03-25T23:12:34+00:00","dateModified":"2024-03-31T20:59:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/"},"wordCount":407,"commentCount":0,"articleSection":["Colaboradores","Tudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/","name":"\u00c9 DE PROP\u00d3SITO: 13 - JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2024-03-25T23:12:34+00:00","dateModified":"2024-03-31T20:59:12+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/e-de-proposito-13-jeito-de-ser-nao-e-o-mesmo-que-diagnostico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"\u00c9 DE PROP\u00d3SITO: 13 &#8211; JEITO DE SER N\u00c3O \u00c9 O MESMO QUE DIAGN\u00d3STICO"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8","name":"Mariana Valle","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","caption":"Mariana Valle"},"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/mvalle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=109426"}],"version-history":[{"count":3,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109426\/revisions"}],"predecessor-version":[{"id":109453,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/109426\/revisions\/109453"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=109426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=109426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=109426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}