﻿{"id":1891,"date":"2007-02-12T20:02:45","date_gmt":"2008-04-19T20:03:46","guid":{"rendered":""},"modified":"2007-02-12T20:02:45","modified_gmt":"2008-04-19T20:03:46","slug":"portugal-nao-aborta-o-aborto","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/","title":{"rendered":"PORTUGAL N&#195;O ABORTA O ABORTO"},"content":{"rendered":"<div class=\"fsc_text\"><p>Ora pois! Com a Igreja Cat\u00f3lica pressionando as par\u00f3quias, a campanha confrontou a imagem de meninos de rua e mulheres padecendo de abortos clandestinos com o de fetos mortos. Quando o melhor \u00e9 prevenir. Mas se a educa\u00e7\u00e3o sexual \u00e9 boicotada e a camisinha maltratada, o que fazer com o tes\u00e3o a todo transe que antecipa a rela\u00e7\u00e3o? Ah, crian\u00e7as, com jeito vai, casem-se e formem uma fam\u00edlia que Deus aben\u00e7oa&#8230; os av\u00f3s para criarem os netos.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ora pois! Com a Igreja Cat\u00f3lica pressionando as par\u00f3quias, a campanha confrontou a imagem de meninos de rua e mulheres padecendo de abortos clandestinos com o de fetos mortos. Quando o melhor \u00e9 prevenir. Mas se a educa\u00e7\u00e3o sexual \u00e9 boicotada e a camisinha maltratada, o que fazer com o tes\u00e3o a todo transe que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1891","post","type-post","status-publish","format-standard","hentry","category-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PORTUGAL N&#195;O ABORTA O ABORTO - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PORTUGAL N&#195;O ABORTA O ABORTO - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Ora pois! Com a Igreja Cat\u00f3lica pressionando as par\u00f3quias, a campanha confrontou a imagem de meninos de rua e mulheres padecendo de abortos clandestinos com o de fetos mortos. Quando o melhor \u00e9 prevenir. Mas se a educa\u00e7\u00e3o sexual \u00e9 boicotada e a camisinha maltratada, o que fazer com o tes\u00e3o a todo transe que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-04-19T20:03:46+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PORTUGAL N&#195;O ABORTA O ABORTO - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/","og_locale":"pt_BR","og_type":"article","og_title":"PORTUGAL N&#195;O ABORTA O ABORTO - Jornal DuGAIO","og_description":"Ora pois! Com a Igreja Cat\u00f3lica pressionando as par\u00f3quias, a campanha confrontou a imagem de meninos de rua e mulheres padecendo de abortos clandestinos com o de fetos mortos. Quando o melhor \u00e9 prevenir. Mas se a educa\u00e7\u00e3o sexual \u00e9 boicotada e a camisinha maltratada, o que fazer com o tes\u00e3o a todo transe que [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-04-19T20:03:46+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"PORTUGAL N&#195;O ABORTA O ABORTO","datePublished":"2008-04-19T20:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/"},"wordCount":90,"commentCount":0,"articleSection":["Croniquetas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/","name":"PORTUGAL N&#195;O ABORTA O ABORTO - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-04-19T20:03:46+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/portugal-nao-aborta-o-aborto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"PORTUGAL N&#195;O ABORTA O ABORTO"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1891"}],"version-history":[{"count":0,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1891\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}