﻿{"id":2362,"date":"2005-06-06T21:13:05","date_gmt":"2008-05-22T21:14:21","guid":{"rendered":""},"modified":"2023-05-17T21:38:33","modified_gmt":"2023-05-18T00:38:33","slug":"pagu","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/","title":{"rendered":"PAGU"},"content":{"rendered":"<div class=\"fsc_text\"><p><P>Patr\u00edcia Galv\u00e3o nasceu de uma tradicional fam\u00edlia paulista. Um dos sonhos da normalista rebelde era conhecer o Cavaleiro da Esperan\u00e7a, Lu\u00eds Carlos Prestes. Os caretas da \u00e9poca detestavam seu linguajar, modo de vestir e suas atitudes extravagantes. Com seus versos sat\u00edricos, deslumbrava pelo seu jeito atrevido.<BR>O poeta Raul Bopp denominou-a Pagu, apresentando-a para a fina flor da intelectualidade paulistana. Foi logo apadrinhada por Oswald de Andrade e sua mulher, Tarsila do Amaral, que a projetaram como a musa da poesia modernista. Desse conv\u00edvio nasceu um romance entre Pagu e Oswald, que abandonou Tarsila, escandalizando a todos com o novo casamento celebrado defronte ao jazigo da fam\u00edlia do escritor.<BR>Em 1931, o casal fundou o tabl\u00f3ide \u201cO Homem do Povo\u201d que, com suas cr\u00edticas irreverentes \u00e0 moral hip\u00f3crita da sociedade paulista, incitou a ira dos estudantes de Direito do Largo S\u00e3o Francisco &#8211; reduto da nata olig\u00e1rquica. Empastelaram o jornal a t\u00edtulo de est\u00e1gio comprobat\u00f3rio para o exerc\u00edcio da profiss\u00e3o.<BR>Pagu participava intensamente da vida pol\u00edtica e logo evoluiu nos quadros da milit\u00e2ncia do Partido Comunista, radicalizando de tal forma que conseguiu afastar seu fundador, Astrogildo Pereira, acusando-o de intelectual. Em 1932, afastou-se de Oswald e do filho Rud\u00e1 para levar uma vida prolet\u00e1ria no Rio de Janeiro &#8211; fam\u00edlia e amor materno, um desvio pequeno-burgu\u00eas. Incumbiu-se de miss\u00f5es do PCB, se valendo do sexo para obter informa\u00e7\u00f5es do inimigo capitalista.<BR>Em 1935, participou do com\u00edcio que lembrava a condena\u00e7\u00e3o \u00e0 morte dos anarquistas Sacco e Vanzetti nos EUA. Tornou-se a primeira presa pol\u00edtica torturada no Brasil. Conseguiu escapar das garras de Filinto Muller e iniciou uma longa viagem pelo mundo. Circulou por Hollywood, foi at\u00e9 a China, viajou pela Transiberiana para Moscou e se decepcionou com o stalinismo. Depois de entrevistar Freud, partiu para a Fran\u00e7a, onde fez contato com Sartre, Ionesco e Arrabal. Ingressou na Juventude Comunista e foi detida numa manifesta\u00e7\u00e3o de rua. N\u00e3o fora a interven\u00e7\u00e3o do embaixador Souza Dantas, teria sido deportada para a Alemanha, j\u00e1 que sua m\u00e3e tinha ascendentes germ\u00e2nicos.<BR>Retornou ao Brasil em frangalhos. Como resto a pagar da Intentona, ficou encarcerada at\u00e9 1940. Lembrou Olga Ben\u00e1rio quando suplicou \u00e0 sua fam\u00edlia para interceder junto a Oswald de Andrade para que pudesse rever Rud\u00e1.<BR>Ressentida com os companheiros e o PCB, vinculou-se ao jornal \u201cA Vanguarda Socialista\u201d. Seu primeiro artigo foi uma cr\u00edtica demolidora ao livro \u201cVida de Lu\u00eds Carlos Prestes\u201d, de Jorge Amado. Posicionou-se contra o chamado teatro esquerdista, s\u00f3 abrindo exce\u00e7\u00e3o para Brecht.<BR>Em 1949, tentou o suic\u00eddio com um tiro na cabe\u00e7a. O cr\u00edtico liter\u00e1rio Geraldo Ferraz j\u00e1 era seu companheiro e assim continuou at\u00e9 o fim de seus dias. Em 1950, n\u00e3o se elegeu para a Assembl\u00e9ia Legislativa de S\u00e3o Paulo pelo PSB e encerrou seu ativismo pol\u00edtico. Ap\u00f3s anos de exerc\u00edcio como agente cultural em Santos, contraiu um c\u00e2ncer e quis morrer no estrangeiro, distante da Pagu que virou um mito. Outro ensaio de suic\u00eddio e o retorno ao Brasil para morrer junto \u00e0 fam\u00edlia em 1962.<BR>Moral da hist\u00f3ria: assim como o Partido Comunista n\u00e3o pode confiar na convers\u00e3o de qualquer burgu\u00eas \u00e0 causa, devido ao insurgente n\u00e3o conseguir abrir m\u00e3o de suas posses, o amor livre est\u00e1 sujeito aos mesmos abalos. Sucumbe \u00e0 lenda envolto em canalhices sexuais em nome da liberdade para romper as cadeias da fam\u00edlia e colide com a imensidade da oferta que propicia o amor. De t\u00e3o genu\u00edno e singular que se pretende exclusivo.<\/P><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Patr\u00edcia Galv\u00e3o nasceu de uma tradicional fam\u00edlia paulista. Um dos sonhos da normalista rebelde era conhecer o Cavaleiro da Esperan\u00e7a, Lu\u00eds Carlos Prestes. Os caretas da \u00e9poca detestavam seu linguajar, modo de vestir e suas atitudes extravagantes. Com seus versos sat\u00edricos, deslumbrava pelo seu jeito atrevido.O poeta Raul Bopp denominou-a Pagu, apresentando-a para a fina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2362","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PAGU - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAGU - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Patr\u00edcia Galv\u00e3o nasceu de uma tradicional fam\u00edlia paulista. Um dos sonhos da normalista rebelde era conhecer o Cavaleiro da Esperan\u00e7a, Lu\u00eds Carlos Prestes. Os caretas da \u00e9poca detestavam seu linguajar, modo de vestir e suas atitudes extravagantes. Com seus versos sat\u00edricos, deslumbrava pelo seu jeito atrevido.O poeta Raul Bopp denominou-a Pagu, apresentando-a para a fina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-22T21:14:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T00:38:33+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAGU - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/","og_locale":"pt_BR","og_type":"article","og_title":"PAGU - Jornal DuGAIO","og_description":"Patr\u00edcia Galv\u00e3o nasceu de uma tradicional fam\u00edlia paulista. Um dos sonhos da normalista rebelde era conhecer o Cavaleiro da Esperan\u00e7a, Lu\u00eds Carlos Prestes. Os caretas da \u00e9poca detestavam seu linguajar, modo de vestir e suas atitudes extravagantes. Com seus versos sat\u00edricos, deslumbrava pelo seu jeito atrevido.O poeta Raul Bopp denominou-a Pagu, apresentando-a para a fina [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-22T21:14:21+00:00","article_modified_time":"2023-05-18T00:38:33+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"PAGU","datePublished":"2008-05-22T21:14:21+00:00","dateModified":"2023-05-18T00:38:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/"},"wordCount":622,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/","name":"PAGU - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-22T21:14:21+00:00","dateModified":"2023-05-18T00:38:33+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/pagu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"PAGU"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2362"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2362\/revisions"}],"predecessor-version":[{"id":108319,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2362\/revisions\/108319"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}