﻿{"id":2368,"date":"2005-01-03T21:23:52","date_gmt":"2008-05-22T21:24:03","guid":{"rendered":""},"modified":"2023-05-17T21:45:28","modified_gmt":"2023-05-18T00:45:28","slug":"o-mais-belo-reveillon","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/","title":{"rendered":"O MAIS BELO R&#201;VEILLON"},"content":{"rendered":"<div class=\"fsc_text\"><p><P>No R\u00e9veillon de 2004, ela entrou na minha vida feito um raio.<BR>\u00c0s primeiras badaladas da meia-noite de sexta-feira 31 de dezembro de 2004<BR>Lenta como s\u00f3 e acontece aos portadores da energia do kundalini<BR>Me encantando<BR>Disse de cara qual o seu projeto irrealizado (ela os tem)<BR>Qual o mal que a aflige<BR>N\u00e3o gostar de press\u00e3o<BR>Dos filhos ela \u00e9 segura e d\u00e1 conta<BR>Do amor, desapegada<BR>E me beija a boca com gosto de champanhe<BR>Um ser feliz e pleno.<BR>N\u00e3o porque conseguiu ficar de cabe\u00e7a pra baixo no i\u00f4ga<BR>Mas porque ri, um sorriso gostoso que engole o oceano e me transportou \u00e0 Via L\u00e1ctea<BR>Na imperturbabilidade da mulher f\u00e9rtil<BR>Gra\u00e7as ao samadhi, a suspens\u00e3o completa da atividade mental<BR>Que realiza a uni\u00e3o do sujeito com o objeto<BR>Ah, se n\u00e3o fosse o cheiro, o que seria do amor?<BR>Cheiro disso, cheiro daquilo, cad\u00ea voc\u00ea, s\u00f3 quero voc\u00ea, meu amor<BR>E te acho em todos recantos<BR>Que teremos de nos refugiar para construir<BR>E s\u00f3 depois de prontos aparecer&#8230;<BR>N\u00e3o vai ser f\u00e1cil<BR>A poesia estimula, o novo intriga, o renascer perturba<BR>O importante \u00e9 que falamos a mesma l\u00edngua.<BR>O oriental<BR>O caminho correto para alcan\u00e7ar<BR>A lua em Sagit\u00e1rio<BR>Coisa de que nunca ouvimos falar<BR>Mas sonhamos em ter<BR>Fazendo-nos imortais<BR>Pois j\u00e1 nos conhec\u00earamos antes<BR>Ademais&#8230; <BR>Pouco lhe assusta meu passado<BR>T\u00e3o dissecado e malconceituado pelas bruxas<BR>Que n\u00e3o sabem ler nas entrelinhas<BR>O in\u00edcio, meio e fim do amor<BR>Como princ\u00edpio<BR>Princ\u00edpio de tudo<BR>O que nos retirou das trevas<BR>N\u00e3o fomos postos para fixarmos nossos olhos, um no outro, \u00e0 toa. Faz sentido. <BR>Tentar esse encontro<BR>T\u00e3o decantado por quantos cruzamos<BR>Encarna\u00e7\u00e3o por encarna\u00e7\u00e3o<BR>A transformar-se numa lenda<BR>Viva em todos os poros<BR>Jogados que fomos em cena<BR>Todos nos olham e se perguntam<BR>Como transformar o complexo em algo t\u00e3o simples<BR>Mas \u00e9 para isso que estamos aqui?<BR>N\u00e3o h\u00e1 como evitar, prevenir e remediar<BR>Paga-se um pre\u00e7o<BR>Recomenda-se ir com uns trocados no bolso<BR>Eles n\u00e3o d\u00e3o troco nem devolu\u00e7\u00e3o<BR>Se voc\u00ea n\u00e3o conferir eles te tiram um peda\u00e7o, um fragmento da alma<BR>S\u00f3 assim entender\u00e1 que a alma existe e foi feita para ser explorada<BR>E a alma implora por conjun\u00e7\u00e3o, comunh\u00e3o<BR>Pela combina\u00e7\u00e3o, pela transfus\u00e3o<BR>Sais minerais que nos curem dos bacilos<BR>Dos vacilos<BR>Que provocam alergias, sudores e o ciclot\u00edmico<BR>Eu \u00e9 que n\u00e3o vou me incomodar com isso!<BR>Se pudesse parar de pensar por um instante<BR>Mas o amor sufoca, esgana e estripa<BR>Caso voc\u00ea n\u00e3o mova uma palha<BR>Se pudesse parar de pensar por um instante<BR>Eu iria at\u00e9 a\u00ed e a cobriria de beijos<BR>Deixando-a louca<BR>Eu arrepiado<BR>Percorrendo seu corpo sem fazer rodeios<BR>Sugado que nem o g\u00eanio da l\u00e2mpada<BR>Se pudesse parar de pensar por um instante<BR>Se pudesse parar de pensar em voc\u00ea<BR>Mas eu n\u00e3o consigo. Adeus Ano Velho!<\/P><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>No R\u00e9veillon de 2004, ela entrou na minha vida feito um raio.\u00c0s primeiras badaladas da meia-noite de sexta-feira 31 de dezembro de 2004Lenta como s\u00f3 e acontece aos portadores da energia do kundaliniMe encantandoDisse de cara qual o seu projeto irrealizado (ela os tem)Qual o mal que a afligeN\u00e3o gostar de press\u00e3oDos filhos ela \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2368","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O MAIS BELO R&#201;VEILLON - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O MAIS BELO R&#201;VEILLON - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"No R\u00e9veillon de 2004, ela entrou na minha vida feito um raio.\u00c0s primeiras badaladas da meia-noite de sexta-feira 31 de dezembro de 2004Lenta como s\u00f3 e acontece aos portadores da energia do kundaliniMe encantandoDisse de cara qual o seu projeto irrealizado (ela os tem)Qual o mal que a afligeN\u00e3o gostar de press\u00e3oDos filhos ela \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-22T21:24:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T00:45:28+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O MAIS BELO R&#201;VEILLON - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/","og_locale":"pt_BR","og_type":"article","og_title":"O MAIS BELO R&#201;VEILLON - Jornal DuGAIO","og_description":"No R\u00e9veillon de 2004, ela entrou na minha vida feito um raio.\u00c0s primeiras badaladas da meia-noite de sexta-feira 31 de dezembro de 2004Lenta como s\u00f3 e acontece aos portadores da energia do kundaliniMe encantandoDisse de cara qual o seu projeto irrealizado (ela os tem)Qual o mal que a afligeN\u00e3o gostar de press\u00e3oDos filhos ela \u00e9 [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-22T21:24:03+00:00","article_modified_time":"2023-05-18T00:45:28+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"O MAIS BELO R&#201;VEILLON","datePublished":"2008-05-22T21:24:03+00:00","dateModified":"2023-05-18T00:45:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/"},"wordCount":461,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/","name":"O MAIS BELO R&#201;VEILLON - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-22T21:24:03+00:00","dateModified":"2023-05-18T00:45:28+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/o-mais-belo-reveillon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"O MAIS BELO R&#201;VEILLON"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2368"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2368\/revisions"}],"predecessor-version":[{"id":108357,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2368\/revisions\/108357"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}