﻿{"id":2412,"date":"2004-12-14T22:37:22","date_gmt":"2008-05-23T22:37:58","guid":{"rendered":""},"modified":"2023-05-17T21:45:30","modified_gmt":"2023-05-18T00:45:30","slug":"censura-em-revista","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/","title":{"rendered":"CENSURA EM REVISTA"},"content":{"rendered":"<div class=\"fsc_text\"><p><P>A moral vigente na Hollywood dos anos 40, exibida nas telas de cinema do mundo inteiro, uma amostra dos padr\u00f5es de censura a interferir no comportamento do ser humano. Com reflexos s\u00e9rios na libido, no que consiste a dec\u00eancia e na no\u00e7\u00e3o de pecado.<BR>Beijos de boca aberta n\u00e3o devem ser mostrados. A beleza do corpo nu ou seminu n\u00e3o torna moral seu uso em filmes. Dan\u00e7as com movimento dos seios e excessivos requebrados, enquanto os p\u00e9s est\u00e3o estacion\u00e1rios, violam os bons costumes.<BR>Adult\u00e9rio e sexo il\u00edcito, \u00e1s vezes necess\u00e1rios ao enredo, n\u00e3o ser\u00e3o tratados explicitamente, preservando a santidade do casamento. Afinal de contas, amor impuro n\u00e3o deve ser exibido como atraente e belo.<BR>Sedu\u00e7\u00e3o e estupro, apenas sugeridos, e somente quando essenciais \u00e0 trama. N\u00e3o mencionar a palavra aborto. N\u00e3o induzir a simpatia da plat\u00e9ia para o lado do crime, do errado, a torcer pelo Mal. N\u00e3o exacerbar vingan\u00e7a nem o uso de bebidas alco\u00f3licas. N\u00e3o retratar a religi\u00e3o com personagens c\u00f4micos ou vil\u00f5es.<BR>Como a mulher sofreu nesse tempo! Ser m\u00e3e \u00e9 padecer no para\u00edso. S\u00f3 se ama uma vez na vida. Vai ver por que o seu filho est\u00e1 berrando, recomenda o marido. Nem pensar a mulher sair sozinha para passear, sinal de que estava se oferecendo. Deselegante a mulher fumar e ficar jogando fuma\u00e7a na cara dos outros. Decote, pernas, at\u00e9 onde mostrar?<BR>Se pudessem, ao menos, ter ouvido Anna Freud: \u201cmentes criativas s\u00e3o conhecidas por resistir a todo tipo de maus-tratos\u201d. Certamente se lembrariam dos seus tempos de crian\u00e7a, quando os rasgos de personalidade ainda n\u00e3o denotavam sinais de domestica\u00e7\u00e3o. \u201cSe voc\u00ea j\u00e1 foi ousada, n\u00e3o permita que a amansem\u201d, observaria Isadora Duncan.<BR>Todo o cipoal de leis, regras e recomenda\u00e7\u00f5es a respeito da boa conduta visam a inibir o exerc\u00edcio do amor. Se \u00e9 bom ou mau, s\u00f3 o saberemos ao final do interl\u00fadio, do intercurso e do acasalamento, que pedem passagem e modera\u00e7\u00e3o nos coment\u00e1rios para n\u00e3o interferir, obstruir e negar um amor maravilhoso porventura nascendo. A censura n\u00e3o tem o poder da onisci\u00eancia e da futurologia, a respeito falou mais alto a Jeanne Moreau de \u201cOs Amantes\u201d e \u201cJules e Jim\u201d: \u201ca idade n\u00e3o protege contra o amor. Mas o amor, na medida certa, protege contra a idade\u201d.<BR>Mas foi na d\u00e9cada de 60 que as mulheres se libertaram de m\u00e3es e av\u00f3s castradoras, al\u00e9m de maridos que lhes exigiam disciplina, em que Nelson Rodrigues deixou de ser considerado um autor maldito e boca-suja, enquanto Joan Baez deitava e rolava em Woodstock: \u201cvoc\u00ea n\u00e3o pode escolher como vai morrer ou quando. Voc\u00ea s\u00f3 pode decidir como vai viver agora\u201d.<BR>A censura n\u00e3o resistiu e morreu.<\/P><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A moral vigente na Hollywood dos anos 40, exibida nas telas de cinema do mundo inteiro, uma amostra dos padr\u00f5es de censura a interferir no comportamento do ser humano. Com reflexos s\u00e9rios na libido, no que consiste a dec\u00eancia e na no\u00e7\u00e3o de pecado.Beijos de boca aberta n\u00e3o devem ser mostrados. A beleza do corpo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2412","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CENSURA EM REVISTA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CENSURA EM REVISTA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"A moral vigente na Hollywood dos anos 40, exibida nas telas de cinema do mundo inteiro, uma amostra dos padr\u00f5es de censura a interferir no comportamento do ser humano. Com reflexos s\u00e9rios na libido, no que consiste a dec\u00eancia e na no\u00e7\u00e3o de pecado.Beijos de boca aberta n\u00e3o devem ser mostrados. A beleza do corpo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-23T22:37:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T00:45:30+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CENSURA EM REVISTA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/","og_locale":"pt_BR","og_type":"article","og_title":"CENSURA EM REVISTA - Jornal DuGAIO","og_description":"A moral vigente na Hollywood dos anos 40, exibida nas telas de cinema do mundo inteiro, uma amostra dos padr\u00f5es de censura a interferir no comportamento do ser humano. Com reflexos s\u00e9rios na libido, no que consiste a dec\u00eancia e na no\u00e7\u00e3o de pecado.Beijos de boca aberta n\u00e3o devem ser mostrados. A beleza do corpo [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-23T22:37:58+00:00","article_modified_time":"2023-05-18T00:45:30+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"CENSURA EM REVISTA","datePublished":"2008-05-23T22:37:58+00:00","dateModified":"2023-05-18T00:45:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/"},"wordCount":491,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/","name":"CENSURA EM REVISTA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-23T22:37:58+00:00","dateModified":"2023-05-18T00:45:30+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/censura-em-revista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"CENSURA EM REVISTA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2412"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2412\/revisions"}],"predecessor-version":[{"id":108358,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2412\/revisions\/108358"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}