﻿{"id":2420,"date":"2004-05-10T22:44:20","date_gmt":"2008-05-23T22:45:00","guid":{"rendered":""},"modified":"2023-05-17T22:02:51","modified_gmt":"2023-05-18T01:02:51","slug":"habito-ou-vicio","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/","title":{"rendered":"H&#193;BITO OU V&#205;CIO?"},"content":{"rendered":"<div class=\"fsc_text\"><p><P>Ad\u00e3o e Eva obrigaram o mundo a dividir a ma\u00e7\u00e3 do amor em disciplinados e n\u00e3o-disciplinados.<BR>Os disciplinados necessitam ser workaholic na vida em fam\u00edlia, como trabalhadores compulsivos voltados para bem criar os filhos, a salvo das intemp\u00e9ries e m\u00e1s influ\u00eancias que rondam na pretens\u00e3o de desestabilizar o equil\u00edbrio do lar. O objetivo, marcado a ferro em brasa na testa, serve para preveni-los do perigo do descaminho. H\u00e1 que se manter na linha reta. Sob tens\u00e3o, pois o inimigo espreita. Condicionam-se a manter em bom funcionamento a estrutura da c\u00e9lula familiar. Os jovens, por exemplo, n\u00e3o querem largar a casa dos pais, por temerem a viol\u00eancia e o desemprego; s\u00e3o favor\u00e1veis ao exame antidoping na escola . O bem-estar alcan\u00e7ado n\u00e3o pode, em hip\u00f3tese alguma, ser arranhado por m\u00e1s companhias, quizumbas e desconcentra\u00e7\u00e3o no futuro. Caso contr\u00e1rio, a ciz\u00e2nia se instala; exige-se vigil\u00e2ncia para que o mal maior n\u00e3o sobrevenha e rompa com a harmonia.<BR>A vigil\u00e2ncia resulta num v\u00edcio atrelado \u00e0 perdura\u00e7\u00e3o da felicidade desencadeando mecanismos de controle que estimulam a paran\u00f3ia na raz\u00e3o direta de se proteger. Uma boa desculpa \u00e9 a seguran\u00e7a, outrora a sa\u00fade, no futuro, a crian\u00e7a se tornar adulta antes do tempo. A brincadeira virar a s\u00e9rio. A menstrua\u00e7\u00e3o se antecipar. As gincanas se transformarem em testes de intelig\u00eancia, a finalidade \u00e9 descobrir g\u00eanios. Os esportes deixarem de ser lazer e porem em risco a vida. O computador substituir a hora do recreio. Arrisquem largar um simples h\u00e1bito para imaginar como \u00e9 dif\u00edcil, quando n\u00e3o imposs\u00edvel, abandonar um v\u00edcio.<BR>O universo dos indisciplinados n\u00e3o \u00e9 uno e coeso, j\u00e1 que a anarquia prepondera. Pin\u00e7ados ao l\u00e9u: drogados, cujo v\u00edcio os dirige ao inferno psicod\u00e9lico de Dante; alco\u00f3latras, mergulhados num po\u00e7o sem fundo; tabagistas, rumo ao c\u00e2ncer no pulm\u00e3o em alta velocidade. Que diferen\u00e7a faz se a morte nas drogas chega mais r\u00e1pido e no fumo mais lento, se o ser humano se consome na insatisfa\u00e7\u00e3o com sua perspectiva de vida no s\u00e9culo XXI, onde a morte vem sendo banalizada? As drogas apenas aceleram o final desse filme trash. Bons os tempos de inoc\u00eancia, um cigarrinho agora ca\u00eda bem, inofensivos os mata-ratos que se transformaram em cigarros de filtro. Duas doses de u\u00edsque ao chegar do trabalho n\u00e3o fazem mal a ningu\u00e9m, acalma o esp\u00edrito, n\u00e3o passa disso.<BR>Quem garante? Parece promessa do noivo pra noiva na \u00e9poca do tabu da virgindade, mal suportando esperar a hora dela chegar. O mundo se dividia, ent\u00e3o, entre os que tinham ido para a cama com algu\u00e9m e os abst\u00eamios, uma verdadeira guerra fria que dependia da coragem em ultrapassar essa fronteira para fundir as emo\u00e7\u00f5es de dois universos antag\u00f4nicos: a mulher ser obrigada a ter uma vida pura e o homem um salvo-conduto para uma vida dupla. Eles, verdadeiros professores, a ensinar na pr\u00e1tica o que elas poderiam fazer com outros se n\u00e3o implicasse em sacril\u00e9gio no casamento.<BR>Mas se o casar correspondia a uma lavagem cerebral de cozinhar, lavar e limpar, se os homens n\u00e3o as sentiam, n\u00e3o sabiam estabelecer a diferen\u00e7a, e o clima de lua-de-mel, um Xanadu distante. Deu no que deu, desorganizou-se a fam\u00edlia, a preval\u00eancia no ato da conquista ao Deus dar\u00e1 e ela o imobilizou ao ficar por cima &#8211; virou luta livre. Antes que o caos se instalasse, uma reuni\u00e3o do condom\u00ednio se esfalfou para p\u00f4r panos quentes na disputa. Em nome dos filhos e do esp\u00edrito santo. Interrompendo o confronto e arrancando a paz a f\u00f3rceps. O nome da fam\u00edlia falou mais alto, uma acomoda\u00e7\u00e3o geol\u00f3gica. O que n\u00e3o impediu os descendentes desse legado de reorganizarem-se em caretas &#8211; estabelecem os limites necess\u00e1rios para a conviv\u00eancia &#8211; e viciados em papo-cabe\u00e7a &#8211; os transgressores da regra -, afinal, a diverg\u00eancia faz parte da evolu\u00e7\u00e3o.<BR>Como n\u00e3o h\u00e1 registro de cultura que n\u00e3o tenha sacado do nada a cerveja, descoberto um ch\u00e1 e da folha enrolar um charuto, em comemora\u00e7\u00e3o a um triunfo retumbante ou como sintoma de decad\u00eancia, o v\u00edcio levou a melhor. Os caretas em regime de prontid\u00e3o, os indisciplinados a virar o mundo pelo avesso, o gato e o rato, uma simbiose perfeita.<BR>H\u00e1bito ou v\u00edcio?<\/P><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ad\u00e3o e Eva obrigaram o mundo a dividir a ma\u00e7\u00e3 do amor em disciplinados e n\u00e3o-disciplinados.Os disciplinados necessitam ser workaholic na vida em fam\u00edlia, como trabalhadores compulsivos voltados para bem criar os filhos, a salvo das intemp\u00e9ries e m\u00e1s influ\u00eancias que rondam na pretens\u00e3o de desestabilizar o equil\u00edbrio do lar. O objetivo, marcado a ferro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2420","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H&#193;BITO OU V&#205;CIO? - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H&#193;BITO OU V&#205;CIO? - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Ad\u00e3o e Eva obrigaram o mundo a dividir a ma\u00e7\u00e3 do amor em disciplinados e n\u00e3o-disciplinados.Os disciplinados necessitam ser workaholic na vida em fam\u00edlia, como trabalhadores compulsivos voltados para bem criar os filhos, a salvo das intemp\u00e9ries e m\u00e1s influ\u00eancias que rondam na pretens\u00e3o de desestabilizar o equil\u00edbrio do lar. O objetivo, marcado a ferro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-23T22:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T01:02:51+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H&#193;BITO OU V&#205;CIO? - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/","og_locale":"pt_BR","og_type":"article","og_title":"H&#193;BITO OU V&#205;CIO? - Jornal DuGAIO","og_description":"Ad\u00e3o e Eva obrigaram o mundo a dividir a ma\u00e7\u00e3 do amor em disciplinados e n\u00e3o-disciplinados.Os disciplinados necessitam ser workaholic na vida em fam\u00edlia, como trabalhadores compulsivos voltados para bem criar os filhos, a salvo das intemp\u00e9ries e m\u00e1s influ\u00eancias que rondam na pretens\u00e3o de desestabilizar o equil\u00edbrio do lar. O objetivo, marcado a ferro [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-23T22:45:00+00:00","article_modified_time":"2023-05-18T01:02:51+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"H&#193;BITO OU V&#205;CIO?","datePublished":"2008-05-23T22:45:00+00:00","dateModified":"2023-05-18T01:02:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/"},"wordCount":783,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/","name":"H&#193;BITO OU V&#205;CIO? - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-23T22:45:00+00:00","dateModified":"2023-05-18T01:02:51+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/habito-ou-vicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"H&#193;BITO OU V&#205;CIO?"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2420"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2420\/revisions"}],"predecessor-version":[{"id":108407,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2420\/revisions\/108407"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}