﻿{"id":2442,"date":"2004-05-03T23:05:34","date_gmt":"2008-05-23T23:06:15","guid":{"rendered":""},"modified":"2023-05-17T22:02:53","modified_gmt":"2023-05-18T01:02:53","slug":"amizade-entre-homem-e-mulher","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/","title":{"rendered":"AMIZADE ENTRE HOMEM E MULHER"},"content":{"rendered":"<div class=\"fsc_text\"><p><P>O que impede uma amizade desinteressada num casal de amigos crescer em propor\u00e7\u00e3o geom\u00e9trica a tal ponto que o povo comentaria \u201ca\u00ed tem\u201d? Amor? N\u00e3o \u00e9 poss\u00edvel ao homem e mulher conjuminarem id\u00e9ias, esp\u00edrito, g\u00eanio, intelig\u00eancia e senso de humor, que, de repente, acaba surgindo o interesse afetivo, a cumplicidade emocional ou simplesmente o tes\u00e3o? Ou a mulher teria de se valer das costas largas gay? Amparando-se em pessoas que costumam ser mais confi\u00e1veis, pelo fato de n\u00e3o as amea\u00e7arem. O interesse do falo \u00e9 outro.<BR>E se o sexo se inserir na rela\u00e7\u00e3o desinteressada? Afian\u00e7am os interessados, sem que haja amor. Se deixar rolar, \u00e9 parque de divers\u00f5es, puro divertimento, a adrenalina da montanha-russa no trem-fantasma que nos conduz ao carrossel do amor. J\u00e1 que procuraram o caminho das pedras mais f\u00e1cil, pura covardia, que saibam distinguir amizade de amor e optem pelo que prefere. Pois se confundir alhos com bugalhos, voc\u00ea estar\u00e1 obrigado a se manter a uma dist\u00e2ncia cr\u00edtica de seu irm\u00e3o camarada. E respeitar. Segurar sua onda. N\u00e3o brincar com o perigo. Sob o risco de perder um ente querido que, por vezes, vale mais do que um consang\u00fc\u00edneo.<BR>Ah, n\u00e3o se pode pretender falar a s\u00e9rio sobre o assunto que se pensa logo em amizade colorida! Em ficar. Em apelar para o rasteiro, onde as cobras andam r\u00e1pido e gavi\u00e3o avoa que nem avi\u00e3o &#8211; para dar uma beliscada, meu irm\u00e3o! J\u00e1 que n\u00e3o tem tu, vai tu mesmo! N\u00e3o complica, \u00e9 como procurar agulha no palheiro, homem e mulher estarem com a mesma proposta.<BR>Contudo, quando a amizade traduz uma verdade que n\u00e3o se encontra descrita em nenhum vern\u00e1culo, o sexo fica encurralado. Se deixar o sexo entrar, o encanto da amizade se esfuma\u00e7a, quando n\u00e3o macula. Quebra a virgindade do princ\u00edpio. No lugar-comum da procura por um parceiro afetivo, cai-se no af\u00e3 e confunde-se os canais.<BR>Para o homem, corresponde aos doze trabalhos de H\u00e9rcules evitar a queda no po\u00e7o sem fundo do facilit\u00e1rio sexual. Tem que matar um le\u00e3o por dia para provar a si mesmo que \u00e9 homem. Norteia-se pela alimenta\u00e7\u00e3o para se nutrir do b\u00e1sico. Coloca o sexo acima da amizade. Se for mais sofisticado, pelo ato da conquista inspirado em Casanova, beirando o rid\u00edculo de esnobar o gozo farto para mant\u00ea-la atada \u00e0 fantasia.<BR>J\u00e1 o que confunde a mulher \u00e9 quando busca um parceiro, em busca de um tempo perdido. O sexo tumultuar\u00e1 uma amizade constru\u00edda a conta-gotas, j\u00f3ia rara lapidada \u00e0 luz de velas. Que nos fazem suspirar. Num misto de romantismo e al\u00edvio por encontrar uma cara-metade fiel aos princ\u00edpios, digno de merecer seu carinho e abrir o cora\u00e7\u00e3o para o que der e vier.<BR>Tem amigo que vira namorado, tem namorado que vira amigo, tem namorado que nunca vira amigo, tem amigo que nunca vira namorado.<\/P><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>O que impede uma amizade desinteressada num casal de amigos crescer em propor\u00e7\u00e3o geom\u00e9trica a tal ponto que o povo comentaria \u201ca\u00ed tem\u201d? Amor? N\u00e3o \u00e9 poss\u00edvel ao homem e mulher conjuminarem id\u00e9ias, esp\u00edrito, g\u00eanio, intelig\u00eancia e senso de humor, que, de repente, acaba surgindo o interesse afetivo, a cumplicidade emocional ou simplesmente o tes\u00e3o? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2442","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMIZADE ENTRE HOMEM E MULHER - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMIZADE ENTRE HOMEM E MULHER - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"O que impede uma amizade desinteressada num casal de amigos crescer em propor\u00e7\u00e3o geom\u00e9trica a tal ponto que o povo comentaria \u201ca\u00ed tem\u201d? Amor? N\u00e3o \u00e9 poss\u00edvel ao homem e mulher conjuminarem id\u00e9ias, esp\u00edrito, g\u00eanio, intelig\u00eancia e senso de humor, que, de repente, acaba surgindo o interesse afetivo, a cumplicidade emocional ou simplesmente o tes\u00e3o? [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-23T23:06:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T01:02:53+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMIZADE ENTRE HOMEM E MULHER - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/","og_locale":"pt_BR","og_type":"article","og_title":"AMIZADE ENTRE HOMEM E MULHER - Jornal DuGAIO","og_description":"O que impede uma amizade desinteressada num casal de amigos crescer em propor\u00e7\u00e3o geom\u00e9trica a tal ponto que o povo comentaria \u201ca\u00ed tem\u201d? Amor? N\u00e3o \u00e9 poss\u00edvel ao homem e mulher conjuminarem id\u00e9ias, esp\u00edrito, g\u00eanio, intelig\u00eancia e senso de humor, que, de repente, acaba surgindo o interesse afetivo, a cumplicidade emocional ou simplesmente o tes\u00e3o? [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-23T23:06:15+00:00","article_modified_time":"2023-05-18T01:02:53+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"AMIZADE ENTRE HOMEM E MULHER","datePublished":"2008-05-23T23:06:15+00:00","dateModified":"2023-05-18T01:02:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/"},"wordCount":515,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/","name":"AMIZADE ENTRE HOMEM E MULHER - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-23T23:06:15+00:00","dateModified":"2023-05-18T01:02:53+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/amizade-entre-homem-e-mulher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"AMIZADE ENTRE HOMEM E MULHER"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2442"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2442\/revisions"}],"predecessor-version":[{"id":108409,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2442\/revisions\/108409"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}