﻿{"id":2462,"date":"2003-05-26T23:27:55","date_gmt":"2008-05-23T23:28:06","guid":{"rendered":""},"modified":"2023-05-17T22:12:46","modified_gmt":"2023-05-18T01:12:46","slug":"confucio-ainda-esta-entre-nos","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/","title":{"rendered":"CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S"},"content":{"rendered":"<div class=\"fsc_text\"><p>Conf\u00facio viveu no s\u00e9culo VI a.C desenvolvendo id\u00e9ias difundidas gra\u00e7as aos c\u00e9us que conspiram a favor. Essa falta de l\u00f3gica quase coerente refletiria a grande for\u00e7a do confucionismo. Quem poderia provar que estava errado, se, com ast\u00facia, poder-se-ia usar para provar que quase tudo estava certo. Ao longo de sua vida pleiteou um cargo administrativo elevado para que pudesse colocar suas id\u00e9ias em pr\u00e1tica. Imagine se os boas-vidas dos governantes iriam dar uma chance ao desmancha-prazeres para interferir em seus dom\u00ednios. Ningu\u00e9m emprega jovens s\u00e9rios e honestos que acreditam ser poss\u00edvel dividir o seu vasto conhecimento com o mundo.<br \/>Decidiu fundar uma escola que iria ensinar administradores pol\u00edticos a governar. Era essencialmente um professor de moral, como se comportar de forma adequada se o que se desejava era governar as pessoas. Primeiro, deveriam saber como governar a si mesmos. Obteve sucesso devido \u00e0 sua personalidade carism\u00e1tica com aulas ministradas \u00e0 sombra de \u00e1rvores: \u201co homem superior \u00e9 comedido em palavras mas n\u00e3o em realiza\u00e7\u00f5es\u201d, \u201cquem n\u00e3o corrige seus erros torna-se ainda mais errado&#8221;.<br \/>No entanto, nem todas as palavras de Conf\u00facio foram banais, algumas s\u00e3o controversas, outras obscuras ou enigm\u00e1ticas, mas no fundo, \u201cquem n\u00e3o conhece o valor das palavras jamais compreender\u00e1 os homens\u201d. Cad\u00ea o eco?<br \/>Sua educa\u00e7\u00e3o certamente influenciou a arte de governar e cumprir com as obriga\u00e7\u00f5es da mesma forma que um pai deve ter para com seu filho. Uma revolu\u00e7\u00e3o comportamental buscando o m\u00e1ximo na virtude, em amar o pr\u00f3ximo, o preceito moral mais profundo da humanidade, proferido por Conf\u00facio quinhentos anos antes do nascimento de Cristo, sem nenhum sentido religioso.<br \/>Muitos alunos de Conf\u00facio se tornaram administradores de grande sucesso, assim que entravam em contato com a realidade do poder, deixavam de lado seus princ\u00edpios. Mal que ainda se pratica hoje.<br \/>Desfez a lenda de que os governantes eram descendentes de ancestrais divinos, atuando por decreto celeste. O Estado deveria se tornar um empreendimento cooperativista, em benef\u00edcio de todos. Dissuadiu seus senhores de se envolverem em guerras irracionais com cidades-estados escravas que rompiam constantemente suas alian\u00e7as para dar vaz\u00e3o a massacres, orgias e deprava\u00e7\u00e3o, de forma a n\u00e3o se reduzirem \u00e0 miserabilidade de disputas sem-fim.<br \/>Se libertos desse sofrimento advindo da viol\u00eancia, a sociedade fatalmente iria mudar, deixando de ser usada como mero pretexto para os excessos de seus governantes. Paradigma do qual n\u00e3o nos libertamos ainda.<br \/>Finalmente, aos 50 anos, foi nomeado Ministro do Crime, e aplicou a pena de morte com tal rigor que os ladr\u00f5es desapareceram, estendendo-a inclusive \u00e0queles que inventavam roupas fora do comum a quebrar uma harmonia sempre respeitada nos costumes chineses &#8211; Mao Ts\u00e9-tung, que o elegeu como o seu maior desafeto, o imitaria na Revolu\u00e7\u00e3o Cultural. Passou dos limites quando exigiu que nas prov\u00edncias os homens s\u00f3 andassem pelo lado direito da rua, para que n\u00e3o se misturassem \u00e0s mulheres, \u00e0 sua esquerda.<br \/>A classe dominante n\u00e3o aproveitou o que seria considerada a maior sabedoria de todos os tempos na China, sem aceitar um \u00fanico suborno ou jamais trair seu senhor junto aos seus inimigos. Seus ensinamentos determinaram as normas de conduta e foram o alimento espiritual da burocracia chinesa, se transformando numa religi\u00e3o por for\u00e7a de sua moral e \u00e9tica implantadas, o que certamente contribuiu para a sua longevidade de mais de 2 mil anos.<br \/>A China de Mao extinguiu a China de Conf\u00facio, em que o t\u00e9dio era uma ben\u00e7\u00e3o, sossegadas as propinas e a infidelidade pol\u00edtica. Conf\u00facio morreu lamentando que ningu\u00e9m o entendia, julgando-se um fracasso, \u201cos \u00fanicos que jamais mudam s\u00e3o os s\u00e1bios e os idiotas\u201d. Quem somos n\u00f3s para contrariar algu\u00e9m t\u00e3o s\u00e1bio?<br \/>Quem falou tanto em esperan\u00e7a e governa com medo n\u00e3o tem uma escuta boa para Conf\u00facio: \u201co homem realizado procura o que existe dentro de si, o frustrado procura o que aparece nos outros\u201d. Necessita da aquiesc\u00eancia de fantasmas que j\u00e1 sentaram no trono e de m\u00famias que negociam poder, uns desmancha-prazeres que banem radicais, evitando chegar \u00e0 raiz dos problemas ao dar um tiro no p\u00e9.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Conf\u00facio viveu no s\u00e9culo VI a.C desenvolvendo id\u00e9ias difundidas gra\u00e7as aos c\u00e9us que conspiram a favor. Essa falta de l\u00f3gica quase coerente refletiria a grande for\u00e7a do confucionismo. Quem poderia provar que estava errado, se, com ast\u00facia, poder-se-ia usar para provar que quase tudo estava certo. Ao longo de sua vida pleiteou um cargo administrativo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2462","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Conf\u00facio viveu no s\u00e9culo VI a.C desenvolvendo id\u00e9ias difundidas gra\u00e7as aos c\u00e9us que conspiram a favor. Essa falta de l\u00f3gica quase coerente refletiria a grande for\u00e7a do confucionismo. Quem poderia provar que estava errado, se, com ast\u00facia, poder-se-ia usar para provar que quase tudo estava certo. Ao longo de sua vida pleiteou um cargo administrativo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-23T23:28:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T01:12:46+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/","og_locale":"pt_BR","og_type":"article","og_title":"CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S - Jornal DuGAIO","og_description":"Conf\u00facio viveu no s\u00e9culo VI a.C desenvolvendo id\u00e9ias difundidas gra\u00e7as aos c\u00e9us que conspiram a favor. Essa falta de l\u00f3gica quase coerente refletiria a grande for\u00e7a do confucionismo. Quem poderia provar que estava errado, se, com ast\u00facia, poder-se-ia usar para provar que quase tudo estava certo. Ao longo de sua vida pleiteou um cargo administrativo [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-23T23:28:06+00:00","article_modified_time":"2023-05-18T01:12:46+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S","datePublished":"2008-05-23T23:28:06+00:00","dateModified":"2023-05-18T01:12:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/"},"wordCount":730,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/","name":"CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-23T23:28:06+00:00","dateModified":"2023-05-18T01:12:46+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/confucio-ainda-esta-entre-nos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"CONF&#218;CIO AINDA EST&#193; ENTRE N&#211;S"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2462"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2462\/revisions"}],"predecessor-version":[{"id":108483,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2462\/revisions\/108483"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}