﻿{"id":2616,"date":"2003-02-10T07:50:01","date_gmt":"2008-05-26T07:50:15","guid":{"rendered":""},"modified":"2023-05-17T22:16:26","modified_gmt":"2023-05-18T01:16:26","slug":"esperanca-ou-medo","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/","title":{"rendered":"ESPERAN&#199;A OU MEDO?"},"content":{"rendered":"<div class=\"fsc_text\"><p><P>Schopenhauer (1788-1860) foi o primeiro fil\u00f3sofo a proclamar que o \u00e2mago do mundo \u00e9 irracional, fundamentalmente oposto \u00e0 intelig\u00eancia e \u00e0 raz\u00e3o, enaltecidas pelos gregos e exaltadas no Iluminismo. O poder de fato que causa todos os sofrimentos. Os seres humanos n\u00e3o passam de objetos da vontade &#8211; a raiz metaf\u00edsica do mundo, a ess\u00eancia de todas as coisas -, para alcan\u00e7ar seus objetivos e perpetuar a esp\u00e9cie. Refutou categoricamente a conceitua\u00e7\u00e3o que vinha desde Arist\u00f3teles, uma extens\u00e3o insepar\u00e1vel do conhecimento, a vontade.<BR>Por ser um \u00edmpeto cego e irresist\u00edvel, a causa primeira e irredut\u00edvel do Ser, a fonte de todas as iniciativas, o instinto gratuito que detona a pot\u00eancia do querer viver, a \u00fanica e verdadeira realidade num mundo no qual todo o resto \u00e9 pura apar\u00eancia ou mera representa\u00e7\u00e3o, a vontade \u00e9 insaci\u00e1vel. O que a vontade sempre quer \u00e9 a vida, o palco onde a manifesta\u00e7\u00e3o da vontade representa. Em busca da satisfa\u00e7\u00e3o ou do que comumente chamamos de felicidade.<BR>Por havermos perdido contato com a M\u00e3e Natureza, conectados \u00e0 internet e filhotes da globaliza\u00e7\u00e3o, estamos, cada vez mais, menos c\u00f4nscios de gra\u00e7as e vantagens com que nascemos ou adquirimos, que fariam jus a ora\u00e7\u00f5es e pensamentos positivos em louvor. Mas n\u00e3o, n\u00e3o lhes damos o devido valor, consideramos apenas como coisas naturais, nada que nos retire da rotina e do ins\u00edpido papel a que nos relegamos, posto que desacreditamos na vontade pol\u00edtica de mudar o atual estado de coisas ao transferirmos a responsabilidade para os eleitos e lavarmos as m\u00e3os, o voto c\u00ednico de quem critica a arquitetura do projeto e n\u00e3o quer se comprometer com a distribui\u00e7\u00e3o mais eq\u00fcitativa das benesses que a sociedade amealha e com a amplia\u00e7\u00e3o dos direitos do cidad\u00e3o.<BR>Como resultado, priva\u00e7\u00e3o, perdas, corrup\u00e7\u00e3o e retardo na evolu\u00e7\u00e3o em linha direta com os aquinhoados atrav\u00e9s da inseguran\u00e7a e criminalidade desvairada. S\u00f3 depois de perder o que mais amamos ou necessitamos \u00e9 que ficamos sens\u00edveis ao seu real valor. Acostumamo-nos a descrer da honorabilidade do aparelho policial e do senso da Justi\u00e7a, com o interesse p\u00fablico lan\u00e7ado em pocilgas. O que proporciona uma satisfa\u00e7\u00e3o de sinal negativo, de conformismo a um mundo de expia\u00e7\u00f5es, pautados pela afli\u00e7\u00e3o e preocupa\u00e7\u00e3o em nos manter \u00edntegros e dignos para evitar maiores sofrimentos, em meio \u00e0 dor de amar, inveja, ambi\u00e7\u00e3o, \u00f3dio, ci\u00fame, ang\u00fastia, avareza, e fracasso.<BR>O que levou os c\u00ednicos a se valerem do Marqu\u00eas de Sade e vincularem a dor do menos pior melhor do que o pior, ao prazer do melhor ser inimigo do bom. Uma conflu\u00eancia mafiosa que nos desvencilha da ilus\u00e3o de que agimos racionalmente, estamos a servi\u00e7o da irracionalidade da vontade de querer viver, o que nos obriga a guerrear para evoluir, gra\u00e7as a essa for\u00e7a tir\u00e2nica, voraz e brutal que rege a nossa esp\u00e9cie.<BR>Esses convictos na impossibilidade de conciliar lei com virtude mereceriam percorrer, sob vara, os corredores de hospitais, enfermarias, salas de cirurgia, pres\u00eddios, delegacias. O parco interior dos barracos, a escura morada da mis\u00e9ria. Os campos de batalha e locais de execu\u00e7\u00e3o sum\u00e1ria. Retribuir\u00e3o, decerto, com uma fria curiosidade, em contraste flagrante com o olhar de dois amantes quando se entrecruzam \u00e1vidos de desejo e dispostos a modificar o estado habitual das coisas. Servil, s\u00f3 ao amor.<BR>Somos suficientemente orgulhosos para nos declararmos perfeitamente livres e virarmos a vida pelo avesso, nos tornando outra pessoa. Posteriormente, descobrimos que a liberdade, apesar de todas as reflex\u00f5es e resolu\u00e7\u00f5es, \u00e9 um bem raro. Sujeitamo-nos a necessidades e aceitamos o papel que hav\u00edamos condenado, representando at\u00e9 o fim.<BR>Escolha sua op\u00e7\u00e3o: esperan\u00e7a ou medo?<BR><\/P><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Schopenhauer (1788-1860) foi o primeiro fil\u00f3sofo a proclamar que o \u00e2mago do mundo \u00e9 irracional, fundamentalmente oposto \u00e0 intelig\u00eancia e \u00e0 raz\u00e3o, enaltecidas pelos gregos e exaltadas no Iluminismo. O poder de fato que causa todos os sofrimentos. Os seres humanos n\u00e3o passam de objetos da vontade &#8211; a raiz metaf\u00edsica do mundo, a ess\u00eancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2616","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESPERAN&#199;A OU MEDO? - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESPERAN&#199;A OU MEDO? - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Schopenhauer (1788-1860) foi o primeiro fil\u00f3sofo a proclamar que o \u00e2mago do mundo \u00e9 irracional, fundamentalmente oposto \u00e0 intelig\u00eancia e \u00e0 raz\u00e3o, enaltecidas pelos gregos e exaltadas no Iluminismo. O poder de fato que causa todos os sofrimentos. Os seres humanos n\u00e3o passam de objetos da vontade &#8211; a raiz metaf\u00edsica do mundo, a ess\u00eancia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-26T07:50:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T01:16:26+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESPERAN&#199;A OU MEDO? - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/","og_locale":"pt_BR","og_type":"article","og_title":"ESPERAN&#199;A OU MEDO? - Jornal DuGAIO","og_description":"Schopenhauer (1788-1860) foi o primeiro fil\u00f3sofo a proclamar que o \u00e2mago do mundo \u00e9 irracional, fundamentalmente oposto \u00e0 intelig\u00eancia e \u00e0 raz\u00e3o, enaltecidas pelos gregos e exaltadas no Iluminismo. O poder de fato que causa todos os sofrimentos. Os seres humanos n\u00e3o passam de objetos da vontade &#8211; a raiz metaf\u00edsica do mundo, a ess\u00eancia [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-26T07:50:15+00:00","article_modified_time":"2023-05-18T01:16:26+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"ESPERAN&#199;A OU MEDO?","datePublished":"2008-05-26T07:50:15+00:00","dateModified":"2023-05-18T01:16:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/"},"wordCount":661,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/","name":"ESPERAN&#199;A OU MEDO? - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-26T07:50:15+00:00","dateModified":"2023-05-18T01:16:26+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/esperanca-ou-medo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"ESPERAN&#199;A OU MEDO?"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2616"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2616\/revisions"}],"predecessor-version":[{"id":108500,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2616\/revisions\/108500"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}