﻿{"id":2691,"date":"2002-06-03T14:55:17","date_gmt":"2008-05-26T14:55:26","guid":{"rendered":""},"modified":"2023-05-17T22:23:12","modified_gmt":"2023-05-18T01:23:12","slug":"com-o-rei-na-barriga","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/","title":{"rendered":"COM O REI NA BARRIGA"},"content":{"rendered":"<div class=\"fsc_text\"><p><P>O futebol n\u00e3o cansa de dar bal\u00e3o e liquidar com os donos da verdade que falam grosso em seus progn\u00f3sticos, emplastrando suas caras com tortas sa\u00eddas de padarias t\u00e3o-somente para lambuzar aquele ar arrogante e esnobe de expert. <BR>Justo o que aconteceu com a Fran\u00e7a. Se com ber\u00e7o espl\u00eandido sempre andou de salto alto, imagine a banca de rei do futebol s\u00f3 porque se julga inserida na restrita elite de Brasil, Alemanha, It\u00e1lia e Argentina, sempre respeitados n\u00e3o importa a qualidade do plantel. Se a m\u00edstica da garra do Uruguai j\u00e1 foi para o espa\u00e7o com o maracanazo de 1950. At\u00e9 o senegal\u00eas Vieira, naturalizado franc\u00eas aos 16 anos, que sentenciou a decad\u00eancia do Brasil, n\u00e3o levou f\u00e9 na p\u00e1tria que renegou: qual \u00e9 a relev\u00e2ncia de ser vice-campe\u00e3 da \u00c1frica, se a totalidade de seus jogadores disputam o campeonato franc\u00eas? <BR>Cegueira maior s\u00f3 a da Dinamarca ao trocar as lentes de Martin Laursen em pleno jogo com o Uruguai durante longos 5 minutos, o que nos concede a honra de sermos senegaleses desde criancinha. O Rio 40\u00ba consagrou o calor senegalesco, desculpa jo\u00e3o-sem-bra\u00e7o para calar a antiga campanha difamante sobre a indol\u00eancia e pregui\u00e7a do brasileiro, exce\u00e7\u00e3o feita aos trabalhos sexuais. Contudo, n\u00e3o ser\u00edamos capazes de imitar o liban\u00eas rec\u00e9m-casado Louay, que pediu dispensa de seus deveres conjugais durante as transmiss\u00f5es da Copa, no que a esposa acedeu se retirando para a casa dos pais. <BR>Do mesmo mal padece Roberto Carlos. Em sua incontin\u00eancia verbal se arvora em ocupar a posi\u00e7\u00e3o de psic\u00f3logo, ao inv\u00e9s de lateral: para quem conhece um pouquinho de futebol, com 60% de nossa capacidade, somos imbat\u00edveis e vamos dar espet\u00e1culo. Com o rei na barriga, o castigo veio a cavalo. O rei dos treinos, Emerson, madeira de dar em doido, \u00e9 cortado da sele\u00e7\u00e3o ao luxar o bra\u00e7o como goleiro numa peladinha descompromissada. <BR>Improvisa\u00e7\u00e3o sem talento resulta em estresse, que mal disfar\u00e7a a press\u00e3o com que uma competi\u00e7\u00e3o desse naipe brinca de gato e sapato com o at\u00e1vico sentimento de inferioridade que nos persegue, para que ousemos tirar os p\u00e9s do charco. <BR>Uma das formas de enfiar a carapu\u00e7a de superior \u00e9 correlacionar a conquista da Copa a epop\u00e9ias her\u00f3icas, como os turcos real\u00e7ando seu pedigree com a extens\u00e3o do Imp\u00e9rio Otomano. N\u00e3o chegam a vestir os minaretes das torres de mesquitas com camisetas ou imagens da sele\u00e7\u00e3o, Al\u00e1 n\u00e3o suportaria tais palha\u00e7adas. Agora, dar bal\u00e3o no Roberto Carlos com a bola presa entre os calcanhares, isso pode. A presepada nos estertores finais da partida para faz\u00ea-lo engolir em seco sua l\u00edngua de trapo n\u00e3o \u00e9 despir um rei e colocar outro. A derrota no lombo j\u00e1 estava sacramentada, a expuls\u00e3o de dois turcos e a agress\u00e3o aos pa\u00edses baixos de Rivaldo evidenciaram a chinelada. <BR>Que se amplie o conceito de pa\u00eds de opereta no futebol: o Equador. Depois de brilhar nas eliminat\u00f3rias e alcan\u00e7ar a gl\u00f3ria de disputar sua primeira Copa, virou macarr\u00e3o na boca dos italianos em 20 minutos. Tanta luta para morrer nas praias da \u00c1sia. Lembra a senhora Regina C\u00e9lia, em fase de transi\u00e7\u00e3o para conquistar um novo marido. Organizou uma grande festa, alugou uma bela casa, tomou a frente da decora\u00e7\u00e3o e dos convivas, contratou uma grande orquestra cujos \u00faltimos acordes coincidiriam com o derradeiro casal, se esmerou nos quitutes e no sortimento de bebidas, p\u00f4s seu melhor vestido, recostou sua cabe\u00e7a no travesseiro para rememorar o prazer em cada detalhe da organiza\u00e7\u00e3o, e sonhou&#8230; at\u00e9 acordar no dia seguinte.<\/P><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>O futebol n\u00e3o cansa de dar bal\u00e3o e liquidar com os donos da verdade que falam grosso em seus progn\u00f3sticos, emplastrando suas caras com tortas sa\u00eddas de padarias t\u00e3o-somente para lambuzar aquele ar arrogante e esnobe de expert. Justo o que aconteceu com a Fran\u00e7a. Se com ber\u00e7o espl\u00eandido sempre andou de salto alto, imagine [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[41,20,24,27],"tags":[],"class_list":["post-2691","post","type-post","status-publish","format-standard","hentry","category-coreia-fase-classificatoria-cronica","category-cronicas","category-esporte-cronica","category-futebol-esporte-cronica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COM O REI NA BARRIGA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COM O REI NA BARRIGA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"O futebol n\u00e3o cansa de dar bal\u00e3o e liquidar com os donos da verdade que falam grosso em seus progn\u00f3sticos, emplastrando suas caras com tortas sa\u00eddas de padarias t\u00e3o-somente para lambuzar aquele ar arrogante e esnobe de expert. Justo o que aconteceu com a Fran\u00e7a. Se com ber\u00e7o espl\u00eandido sempre andou de salto alto, imagine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-26T14:55:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T01:23:12+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COM O REI NA BARRIGA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/","og_locale":"pt_BR","og_type":"article","og_title":"COM O REI NA BARRIGA - Jornal DuGAIO","og_description":"O futebol n\u00e3o cansa de dar bal\u00e3o e liquidar com os donos da verdade que falam grosso em seus progn\u00f3sticos, emplastrando suas caras com tortas sa\u00eddas de padarias t\u00e3o-somente para lambuzar aquele ar arrogante e esnobe de expert. Justo o que aconteceu com a Fran\u00e7a. Se com ber\u00e7o espl\u00eandido sempre andou de salto alto, imagine [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-26T14:55:26+00:00","article_modified_time":"2023-05-18T01:23:12+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"COM O REI NA BARRIGA","datePublished":"2008-05-26T14:55:26+00:00","dateModified":"2023-05-18T01:23:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/"},"wordCount":647,"commentCount":0,"articleSection":["Cor\u00e9ia - Fase classificat\u00f3ria","Cr\u00f4nicas","Esporte","Futebol"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/","name":"COM O REI NA BARRIGA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-26T14:55:26+00:00","dateModified":"2023-05-18T01:23:12+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/com-o-rei-na-barriga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"COM O REI NA BARRIGA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2691"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2691\/revisions"}],"predecessor-version":[{"id":108547,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2691\/revisions\/108547"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}