﻿{"id":2726,"date":"2000-09-03T16:23:41","date_gmt":"2008-05-26T16:24:00","guid":{"rendered":""},"modified":"2023-05-17T22:27:45","modified_gmt":"2023-05-18T01:27:45","slug":"queria-poder-amar-mais","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/","title":{"rendered":"QUERIA PODER AMAR MAIS"},"content":{"rendered":"<div class=\"fsc_text\"><p>Os animais segregam ferom\u00f4nios para atrair sexualmente indiv\u00edduos da mesma esp\u00e9cie. As abelhas, em especial, adoram fazer uso de seu arsenal de horm\u00f4nios para ferrar os zang\u00f5es. O mel \u00e9 apenas um disfarce. Melhor seria mapear esse ins\u00f3lito e in\u00f3spito territ\u00f3rio em que nos tornamos seres estranhos a atrair, conquistar, submeter, trocar e trair o pr\u00f3ximo. Do que explorar os segredos que Marte esconde, os an\u00e9is de Saturno, e se depois de Plut\u00e3o a obsess\u00e3o pelo amor, travestido com a m\u00e1scara da onipot\u00eancia, faz a gente acreditar que a vida tem sentido. <BR>Se eu sou capaz de amar tanto, queria poder amar mais. Afinal, o amor \u00e9 v\u00edcio, lux\u00faria, a sublime consci\u00eancia de n\u00e3o ter limites, um querer deixar a marca de sua presen\u00e7a a ferro e fogo, a certeza de que a v\u00edtima ser\u00e1 derrubada. Como as balas \u201cponta oca\u201d, que provocam uma les\u00e3o maior porque se abrem ao atingir o alvo, ampliando a \u00e1rea de destrui\u00e7\u00e3o. Uma nostalgia das origens b\u00e1rbaras em que o car\u00e1ter era moldado pela t\u00eampera do mais forte e o escr\u00fapulo, um embara\u00e7o distante do senso moral.&nbsp; <BR>Por que um homem p\u00f5e tudo a perder por ci\u00fame e capricho? Por que um homem com idade para ser av\u00f4, velho de cabe\u00e7a e jovem no irresist\u00edvel barato de ser v\u00e2ndalo e troglodita, se desestrutura emocionalmente por uma mulher que poderia ser sua neta? A ponto de n\u00e3o ver encruzilhadas e colidir. Trocar de carro e arrebentar as rodas por n\u00e3o enxergar mais buracos na estrada da vida. Arrancar a f\u00f3rceps os e-mails do computador para examinar sua correspond\u00eancia e descobrir com quem vinha trocando id\u00e9ias. Exigir devolu\u00e7\u00e3o de presentes e uma procura\u00e7\u00e3o em branco para que todos os bens havidos na uni\u00e3o retornem ao seu verdadeiro dono. Cortejar sua fam\u00edlia t\u00e3o-somente para controlar seus passos. <BR>Onde termina o amor e come\u00e7a a intimida\u00e7\u00e3o? Insinuar que transmitiu doen\u00e7a ven\u00e9rea \u00e9 argumenta\u00e7\u00e3o f\u00fatil depois da AIDS. Apenas porque se odeia a vida afetiva pregressa, a tudo vivido e constru\u00eddo antes de sua chegada. A chegada do todo-poderoso que n\u00e3o gosta de ser contrariado. A ponto de alugar um apartamento em frente para poder controlar sua vida sexual depois de decretado rei morto, rei posto. O arrogante que instrui seus subordinados sobre como as coisas devem acontecer na vida. O especialista que, se n\u00e3o sentar e escrever o que tem para dizer, vai falar besteira, uma atr\u00e1s da outra. O profissional que projeta o ser amado e depois cobra a conta. O mais ing\u00eanuo dos homens que adora contar vantagens no clube do bolinha ao arrotar que n\u00e3o move uma palha para conquistar as mulheres.<BR>&nbsp;\u201cN\u00e3o quero mais nada meu em voc\u00ea, se quiser rasgar e mandar os trapos para que confira, tudo bem, ia dar de caridade mesmo\u201d &#8211; a bofetada que d\u00f3i mais. <BR>O \u00f3dio \u00e9 uma porta aberta para a maldade. Interpreta ao p\u00e9 da letra o \u00eddolo Orson Welles, \u201ctodos matam as pessoas que amam, de uma forma ou de outra, matam em palavras, em gestos\u201d, e comete a insensatez. Sob forte como\u00e7\u00e3o. Movido pelo orgulho do macho ofendido. Atiram no rosto, nas costas, no ouvido, e carregam as c\u00e1psulas das balas no bolso como recorda\u00e7\u00e3o. Apenas porque elas se cansaram deles. Desses soberanos enrolados na bandeira do tradicional direito \u00e0 propriedade. Querem ir embora. Reconhecem que surtaram ao lado dele e agora merecem uma chance de vida mais sadia. Eles n\u00e3o aceitam e tentam prostitu\u00ed-la, pressionando-as para manterem rela\u00e7\u00f5es sexuais.<BR>E se arru\u00edna a vida por um motivo f\u00fatil. \u201cMotivo f\u00fatil, uma pin\u00f3ia, s\u00f3 se for para quem perdeu a capacidade de amar.\u201d Ruim com um, ruim com todos, n\u00e3o se pensa em outras vidas nessa vida, ou nessa vida em outras vidas, n\u00e3o se pensa sobre o livre-arb\u00edtrio que o conduz pelas m\u00e3os inevitavelmente at\u00e9 aquele ilustre desconhecido na pr\u00f3xima esquina. Caso contr\u00e1rio, ele n\u00e3o se autocondenaria nem pediria perd\u00e3o \u00e0s filhas, por escrito, um ato falho de quem teme a lei do retorno sobre as herdeiras. <BR>Existe ainda uma \u00faltima chance antes de o advogado virar a bab\u00e1 do seu destino. Parar o carro num beco sem sa\u00edda com pouco movimento e tirar a pr\u00f3pria vida. Mas cad\u00ea coragem? Tamb\u00e9m, mudaria apenas o endere\u00e7o do sofrimento, n\u00e3o conseguiria terminar com essa ang\u00fastia no peito da qual tenta fugir desde que nasceu. Capacidade de amar \u00e9 um privil\u00e9gio, uma d\u00e1diva que poucos recebem, para amar voc\u00ea tem que lutar com voc\u00ea mesmo, s\u00f3 vence aquele que \u00e9 divino. <BR>O melhor \u00e9 continuar vivo, em liberdade, mas vivendo o inferno aqui mesmo, entre um e outro copo de u\u00edsque. Fim de noite, um Lexotan para brindar a impot\u00eancia.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Os animais segregam ferom\u00f4nios para atrair sexualmente indiv\u00edduos da mesma esp\u00e9cie. As abelhas, em especial, adoram fazer uso de seu arsenal de horm\u00f4nios para ferrar os zang\u00f5es. O mel \u00e9 apenas um disfarce. Melhor seria mapear esse ins\u00f3lito e in\u00f3spito territ\u00f3rio em que nos tornamos seres estranhos a atrair, conquistar, submeter, trocar e trair o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-2726","post","type-post","status-publish","format-standard","hentry","category-assuntos-gerais-cronicas","category-cronicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QUERIA PODER AMAR MAIS - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QUERIA PODER AMAR MAIS - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Os animais segregam ferom\u00f4nios para atrair sexualmente indiv\u00edduos da mesma esp\u00e9cie. As abelhas, em especial, adoram fazer uso de seu arsenal de horm\u00f4nios para ferrar os zang\u00f5es. O mel \u00e9 apenas um disfarce. Melhor seria mapear esse ins\u00f3lito e in\u00f3spito territ\u00f3rio em que nos tornamos seres estranhos a atrair, conquistar, submeter, trocar e trair o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-26T16:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-18T01:27:45+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QUERIA PODER AMAR MAIS - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/","og_locale":"pt_BR","og_type":"article","og_title":"QUERIA PODER AMAR MAIS - Jornal DuGAIO","og_description":"Os animais segregam ferom\u00f4nios para atrair sexualmente indiv\u00edduos da mesma esp\u00e9cie. As abelhas, em especial, adoram fazer uso de seu arsenal de horm\u00f4nios para ferrar os zang\u00f5es. O mel \u00e9 apenas um disfarce. Melhor seria mapear esse ins\u00f3lito e in\u00f3spito territ\u00f3rio em que nos tornamos seres estranhos a atrair, conquistar, submeter, trocar e trair o [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-05-26T16:24:00+00:00","article_modified_time":"2023-05-18T01:27:45+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"QUERIA PODER AMAR MAIS","datePublished":"2008-05-26T16:24:00+00:00","dateModified":"2023-05-18T01:27:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/"},"wordCount":857,"commentCount":0,"articleSection":["Assuntos gerais","Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/","name":"QUERIA PODER AMAR MAIS - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-05-26T16:24:00+00:00","dateModified":"2023-05-18T01:27:45+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/queria-poder-amar-mais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"QUERIA PODER AMAR MAIS"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2726"}],"version-history":[{"count":1,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2726\/revisions"}],"predecessor-version":[{"id":108602,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2726\/revisions\/108602"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}