﻿{"id":2828,"date":"2008-07-03T13:21:41","date_gmt":"2008-07-09T13:22:12","guid":{"rendered":""},"modified":"2008-07-03T13:21:41","modified_gmt":"2008-07-09T13:22:12","slug":"aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/","title":{"rendered":"ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA"},"content":{"rendered":"<div class=\"fsc_text\"><p>Dividida entre diminuir a fila dos condenados no corredor da morte e sustentar assassinos e estupradores que vagabundeiam em pris\u00f5es perp\u00e9tuas, a Suprema Corte decidiu enquadrar na pena de morte somente os crimes que causarem o fim da v\u00edtima &#8211; olho por olho, dente por dente. Descartaram a pena capital para estupro de crian\u00e7as, o trauma f\u00edsico e psicol\u00f3gico infligido seja qual for sua idade, o n\u00edvel de sadismo, quantas vezes foi violentada e o nefasto hist\u00f3rico de abusos perpetrados contra a pureza da inoc\u00eancia. Poderia induzir ao efeito colateral de aumentar a incid\u00eancia dos estuprados, j\u00e1 que a pena seria a mesma. A sociedade americana se debate entre toler\u00e2ncia zero para a impunidade e transparecer maior senso de humanidade.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dividida entre diminuir a fila dos condenados no corredor da morte e sustentar assassinos e estupradores que vagabundeiam em pris\u00f5es perp\u00e9tuas, a Suprema Corte decidiu enquadrar na pena de morte somente os crimes que causarem o fim da v\u00edtima &#8211; olho por olho, dente por dente. Descartaram a pena capital para estupro de crian\u00e7as, o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2828","post","type-post","status-publish","format-standard","hentry","category-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Dividida entre diminuir a fila dos condenados no corredor da morte e sustentar assassinos e estupradores que vagabundeiam em pris\u00f5es perp\u00e9tuas, a Suprema Corte decidiu enquadrar na pena de morte somente os crimes que causarem o fim da v\u00edtima &#8211; olho por olho, dente por dente. Descartaram a pena capital para estupro de crian\u00e7as, o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-07-09T13:22:12+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/","og_locale":"pt_BR","og_type":"article","og_title":"ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA - Jornal DuGAIO","og_description":"Dividida entre diminuir a fila dos condenados no corredor da morte e sustentar assassinos e estupradores que vagabundeiam em pris\u00f5es perp\u00e9tuas, a Suprema Corte decidiu enquadrar na pena de morte somente os crimes que causarem o fim da v\u00edtima &#8211; olho por olho, dente por dente. Descartaram a pena capital para estupro de crian\u00e7as, o [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-07-09T13:22:12+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA","datePublished":"2008-07-09T13:22:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/"},"wordCount":143,"commentCount":0,"articleSection":["Croniquetas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/","name":"ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-07-09T13:22:12+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/aberracoes-a-que-a-pena-de-morte-sujeita-a-sociedade-americana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"ABERRA&#199;&#213;ES A QUE A PENA DE MORTE SUJEITA A SOCIEDADE AMERICANA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2828"}],"version-history":[{"count":0,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2828\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}