﻿{"id":2835,"date":"2008-07-07T13:25:13","date_gmt":"2008-07-09T13:25:38","guid":{"rendered":""},"modified":"2008-07-07T13:25:13","modified_gmt":"2008-07-09T13:25:38","slug":"da-empafia-a-alma-de-vira-lata","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/","title":{"rendered":"DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA"},"content":{"rendered":"<div class=\"fsc_text\"><p>Ronaldinho Gorducho, volte para os bra\u00e7os da torcida, imploram os nossos 2 maiores pr\u00f3ceres: Ricardo Teixeira e Galv\u00e3o Bueno. O Fen\u00f4meno, sem contrato, deformado pelo peso e abandono dos clubes que disputavam seu passe. O Flamengo aplastrado por Caba\u00f1as, quando comemorava as gl\u00f3rias de Joel Natalino diante do Am\u00e9rica mexicano. O Fluminense, posto abaixo pela emp\u00e1fia tradicionalmente tricolor, oriunda dos tempos de apartheid em que os jogadores, at\u00e9 a d\u00e9cada de 70, entravam pela porta de servi\u00e7o. Encarnado, no melhor estilo, pelo mascarado do Renato Ga\u00facho. Temos camisa e tradi\u00e7\u00e3o, mas descemos vertiginosamente as escadas, ora pela Fran\u00e7a, seja pelo Equador, vindo do M\u00e9xico, por que n\u00e3o atrav\u00e9s do Paraguai? Ser\u00e1 que voltaremos \u00e0 alma de vira-lata, com que Nelson Rodrigues sacudia o nosso brio em 1958?<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ronaldinho Gorducho, volte para os bra\u00e7os da torcida, imploram os nossos 2 maiores pr\u00f3ceres: Ricardo Teixeira e Galv\u00e3o Bueno. O Fen\u00f4meno, sem contrato, deformado pelo peso e abandono dos clubes que disputavam seu passe. O Flamengo aplastrado por Caba\u00f1as, quando comemorava as gl\u00f3rias de Joel Natalino diante do Am\u00e9rica mexicano. O Fluminense, posto abaixo pela [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2835","post","type-post","status-publish","format-standard","hentry","category-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Ronaldinho Gorducho, volte para os bra\u00e7os da torcida, imploram os nossos 2 maiores pr\u00f3ceres: Ricardo Teixeira e Galv\u00e3o Bueno. O Fen\u00f4meno, sem contrato, deformado pelo peso e abandono dos clubes que disputavam seu passe. O Flamengo aplastrado por Caba\u00f1as, quando comemorava as gl\u00f3rias de Joel Natalino diante do Am\u00e9rica mexicano. O Fluminense, posto abaixo pela [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-07-09T13:25:38+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/","og_locale":"pt_BR","og_type":"article","og_title":"DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA - Jornal DuGAIO","og_description":"Ronaldinho Gorducho, volte para os bra\u00e7os da torcida, imploram os nossos 2 maiores pr\u00f3ceres: Ricardo Teixeira e Galv\u00e3o Bueno. O Fen\u00f4meno, sem contrato, deformado pelo peso e abandono dos clubes que disputavam seu passe. O Flamengo aplastrado por Caba\u00f1as, quando comemorava as gl\u00f3rias de Joel Natalino diante do Am\u00e9rica mexicano. O Fluminense, posto abaixo pela [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-07-09T13:25:38+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA","datePublished":"2008-07-09T13:25:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/"},"wordCount":145,"commentCount":0,"articleSection":["Croniquetas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/","name":"DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-07-09T13:25:38+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/da-empafia-a-alma-de-vira-lata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"DA EMP&#193;FIA &#192; ALMA DE VIRA-LATA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2835"}],"version-history":[{"count":0,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2835\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}