﻿{"id":3065,"date":"2008-11-03T00:00:03","date_gmt":"2008-11-02T22:28:33","guid":{"rendered":""},"modified":"2008-11-03T00:00:03","modified_gmt":"2008-11-02T22:28:33","slug":"tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/","title":{"rendered":"TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA"},"content":{"rendered":"<div class=\"fsc_text\"><p>N\u00e3o se fazem mais bab\u00e1s como antigamente. Em Goi\u00e1s, d\u00e3o tapas e chutes em crian\u00e7a de 2 anos, ou quando, a t\u00edtulo de ajudar na educa\u00e7\u00e3o, maltratam adolescentes com defici\u00eancia f\u00edsica e mental, ou mesmo alternam entre irm\u00e3os de 3 e 4 anos, com socos e p\u00e9s na cabe\u00e7a. Em Curitiba, s\u00e3o as acompanhantes de idosas que n\u00e3o t\u00eam a menor paci\u00eancia e n\u00e3o aceitam ordens, quando n\u00e3o desviam o dinheiro da pens\u00e3o para dar boa vida a seus amantes e permitir a eles comprar drogas. N\u00e3o s\u00e3o fatos isolados. Com o governo Lula, nota-se um crescente inconformismo com a profiss\u00e3o de dom\u00e9stica e em ser servi\u00e7al que, por vezes, beira a viol\u00eancia.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>N\u00e3o se fazem mais bab\u00e1s como antigamente. Em Goi\u00e1s, d\u00e3o tapas e chutes em crian\u00e7a de 2 anos, ou quando, a t\u00edtulo de ajudar na educa\u00e7\u00e3o, maltratam adolescentes com defici\u00eancia f\u00edsica e mental, ou mesmo alternam entre irm\u00e3os de 3 e 4 anos, com socos e p\u00e9s na cabe\u00e7a. Em Curitiba, s\u00e3o as acompanhantes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-3065","post","type-post","status-publish","format-standard","hentry","category-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"N\u00e3o se fazem mais bab\u00e1s como antigamente. Em Goi\u00e1s, d\u00e3o tapas e chutes em crian\u00e7a de 2 anos, ou quando, a t\u00edtulo de ajudar na educa\u00e7\u00e3o, maltratam adolescentes com defici\u00eancia f\u00edsica e mental, ou mesmo alternam entre irm\u00e3os de 3 e 4 anos, com socos e p\u00e9s na cabe\u00e7a. Em Curitiba, s\u00e3o as acompanhantes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-02T22:28:33+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/","og_locale":"pt_BR","og_type":"article","og_title":"TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA - Jornal DuGAIO","og_description":"N\u00e3o se fazem mais bab\u00e1s como antigamente. Em Goi\u00e1s, d\u00e3o tapas e chutes em crian\u00e7a de 2 anos, ou quando, a t\u00edtulo de ajudar na educa\u00e7\u00e3o, maltratam adolescentes com defici\u00eancia f\u00edsica e mental, ou mesmo alternam entre irm\u00e3os de 3 e 4 anos, com socos e p\u00e9s na cabe\u00e7a. Em Curitiba, s\u00e3o as acompanhantes de [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2008-11-02T22:28:33+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA","datePublished":"2008-11-02T22:28:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/"},"wordCount":146,"commentCount":0,"articleSection":["Croniquetas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/","name":"TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2008-11-02T22:28:33+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/tome-cuidado-antes-de-colocar-alguem-estranho-dentro-de-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"TOME CUIDADO ANTES DE COLOCAR ALGU&#201;M ESTRANHO DENTRO DE CASA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3065"}],"version-history":[{"count":0,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3065\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}