﻿{"id":3645,"date":"2009-10-05T00:00:03","date_gmt":"2009-10-05T22:30:04","guid":{"rendered":""},"modified":"2009-10-05T00:00:03","modified_gmt":"2009-10-05T22:30:04","slug":"os-dois-roman-polansky","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/","title":{"rendered":"OS DOIS ROMAN POLANSKY"},"content":{"rendered":"<div class=\"fsc_text\"><p>Roman Polansky do bem: o grande autor de filmes extraordin\u00e1rios como \u201cA Dan\u00e7a dos Vampiros\u201d, \u201cO Beb\u00ea de Rosemary\u201d, \u201cChinatown\u201d, \u201cO Pianista\u201d e querido, admirado e reconhecido por todos que amam a s\u00e9tima arte nos \u00faltimos 50 anos, cuja mulher, a atriz Sharon Tate, foi assassinada aos 8 meses de gravidez por um psicopata em 1969, al\u00e9m de sofrer o terror nazista ainda menino, ao perder sua m\u00e3e no campo de concentra\u00e7\u00e3o. Roman Polansky do mal: r\u00e9u confesso de estuprar e sodomizar uma menor de 13 anos em 1977, que s\u00f3 n\u00e3o lutou porque ficou com medo e n\u00e3o tinha para onde ir. O famoso diretor polon\u00eas s\u00f3 n\u00e3o foi preso por abusar de sua fama e promessas de estrelato porque se tornou foragido dos EUA por 32 anos. A pris\u00e3o de Polansky na Su\u00ed\u00e7a, aos 76 anos, est\u00e1 sendo atribu\u00edda \u00e0 intoler\u00e2ncia de ningu\u00e9m poder se achar acima da justi\u00e7a americana. \u00c9 a velha luta entre o bem e o mal que se desenrola no interior da alma humana e se explora na fic\u00e7\u00e3o.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Roman Polansky do bem: o grande autor de filmes extraordin\u00e1rios como \u201cA Dan\u00e7a dos Vampiros\u201d, \u201cO Beb\u00ea de Rosemary\u201d, \u201cChinatown\u201d, \u201cO Pianista\u201d e querido, admirado e reconhecido por todos que amam a s\u00e9tima arte nos \u00faltimos 50 anos, cuja mulher, a atriz Sharon Tate, foi assassinada aos 8 meses de gravidez por um psicopata em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-3645","post","type-post","status-publish","format-standard","hentry","category-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OS DOIS ROMAN POLANSKY - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OS DOIS ROMAN POLANSKY - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Roman Polansky do bem: o grande autor de filmes extraordin\u00e1rios como \u201cA Dan\u00e7a dos Vampiros\u201d, \u201cO Beb\u00ea de Rosemary\u201d, \u201cChinatown\u201d, \u201cO Pianista\u201d e querido, admirado e reconhecido por todos que amam a s\u00e9tima arte nos \u00faltimos 50 anos, cuja mulher, a atriz Sharon Tate, foi assassinada aos 8 meses de gravidez por um psicopata em [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-05T22:30:04+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OS DOIS ROMAN POLANSKY - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/","og_locale":"pt_BR","og_type":"article","og_title":"OS DOIS ROMAN POLANSKY - Jornal DuGAIO","og_description":"Roman Polansky do bem: o grande autor de filmes extraordin\u00e1rios como \u201cA Dan\u00e7a dos Vampiros\u201d, \u201cO Beb\u00ea de Rosemary\u201d, \u201cChinatown\u201d, \u201cO Pianista\u201d e querido, admirado e reconhecido por todos que amam a s\u00e9tima arte nos \u00faltimos 50 anos, cuja mulher, a atriz Sharon Tate, foi assassinada aos 8 meses de gravidez por um psicopata em [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2009-10-05T22:30:04+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"OS DOIS ROMAN POLANSKY","datePublished":"2009-10-05T22:30:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/"},"wordCount":188,"commentCount":0,"articleSection":["Croniquetas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/","name":"OS DOIS ROMAN POLANSKY - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2009-10-05T22:30:04+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/os-dois-roman-polansky\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"OS DOIS ROMAN POLANSKY"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3645"}],"version-history":[{"count":0,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3645\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}