﻿{"id":4883,"date":"2012-08-05T00:00:02","date_gmt":"2012-08-05T16:27:37","guid":{"rendered":""},"modified":"2012-08-05T00:00:02","modified_gmt":"2012-08-05T16:27:37","slug":"capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/","title":{"rendered":"CAP&#205;TULO 2 &#8211; A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O"},"content":{"rendered":"<div class=\"fsc_text\"><div>Roberto Gurgel decepcionou com sua pe\u00e7a acusat\u00f3ria depois de anos a fio de investiga\u00e7\u00e3o pela Procuradoria (desde 2005), ao confessar que n\u00e3o tem provas materiais que comprovem a den\u00fancia e de ter se valido de depoimentos para fechar a novela do mensal\u00e3o, especialmente os de Roberto Jefferson e Marcos Val\u00e9rio, que n\u00e3o merecem o menor cr\u00e9dito. O ideal, se Gurgel fosse competente, teria sido arrancar dos mesmos uma dela\u00e7\u00e3o premiada. O que mais transpareceu da leitura era que os fatos arrolados n\u00e3o nos eram estranhos: uma c\u00f3pia fiel da investiga\u00e7\u00e3o levada a efeito pela CPI do Mensal\u00e3o, com muita compet\u00eancia. N\u00e3o trouxe nada de novo ao que j\u00e1 se sabia, exceto o tom sarc\u00e1stico e ferino com que Gurgel acusou, transparecendo ressentimento com os r\u00e9us, o que ir\u00e1 facilitar o trabalho da defesa, pois \u00e9 sempre bom lembrar que j\u00e1 estamos em fase de julgamento e a vontade de condenar n\u00e3o pode ficar subordinada \u00e0 subjetividade e achismos, para dar lugar ao escrut\u00ednio da corte suprema. Tarefa que se tornou dif\u00edcil com as provas levantadas pelo Gurgel, que preferiu concentrar suas baterias em Jos\u00e9 Dirceu, o primeiro a ser julgado, e enfatizando a forma\u00e7\u00e3o de quadrilha. Desprezando a tese do caixa 2. O primeiro abacaxi a ser descascado pelos ju\u00edzes. A n\u00e3o condena\u00e7\u00e3o de Jos\u00e9 Dirceu implica no esvaziamento do julgamento do mensal\u00e3o. Gurgel jogou todas as suas fichas nessa tese.<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Roberto Gurgel decepcionou com sua pe\u00e7a acusat\u00f3ria depois de anos a fio de investiga\u00e7\u00e3o pela Procuradoria (desde 2005), ao confessar que n\u00e3o tem provas materiais que comprovem a den\u00fancia e de ter se valido de depoimentos para fechar a novela do mensal\u00e3o, especialmente os de Roberto Jefferson e Marcos Val\u00e9rio, que n\u00e3o merecem o menor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-4883","post","type-post","status-publish","format-standard","hentry","category-a-guerra-do-mensalao-croniquetas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAP&#205;TULO 2 - A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAP&#205;TULO 2 - A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"Roberto Gurgel decepcionou com sua pe\u00e7a acusat\u00f3ria depois de anos a fio de investiga\u00e7\u00e3o pela Procuradoria (desde 2005), ao confessar que n\u00e3o tem provas materiais que comprovem a den\u00fancia e de ter se valido de depoimentos para fechar a novela do mensal\u00e3o, especialmente os de Roberto Jefferson e Marcos Val\u00e9rio, que n\u00e3o merecem o menor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-05T16:27:37+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Carlos Gaio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Carlos Gaio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAP&#205;TULO 2 - A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/","og_locale":"pt_BR","og_type":"article","og_title":"CAP&#205;TULO 2 - A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O - Jornal DuGAIO","og_description":"Roberto Gurgel decepcionou com sua pe\u00e7a acusat\u00f3ria depois de anos a fio de investiga\u00e7\u00e3o pela Procuradoria (desde 2005), ao confessar que n\u00e3o tem provas materiais que comprovem a den\u00fancia e de ter se valido de depoimentos para fechar a novela do mensal\u00e3o, especialmente os de Roberto Jefferson e Marcos Val\u00e9rio, que n\u00e3o merecem o menor [&hellip;]","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_author":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2012-08-05T16:27:37+00:00","author":"Antonio Carlos Gaio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Carlos Gaio","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/"},"author":{"name":"Antonio Carlos Gaio","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"headline":"CAP&#205;TULO 2 &#8211; A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O","datePublished":"2012-08-05T16:27:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/"},"wordCount":266,"commentCount":0,"articleSection":["A guerra do mensal\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/","name":"CAP&#205;TULO 2 - A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2012-08-05T16:27:37+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/capitulo-2-a-acusacao-e-copia-da-cpi-do-mensalao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"CAP&#205;TULO 2 &#8211; A ACUSA&#199;&#195;O &#201; C&#211;PIA DA CPI DO MENSAL&#195;O"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/fd9f5473d82adc8c0b9c4dac6004e97a","name":"Antonio Carlos Gaio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907bef3ce6856ee9e843b72f479d32a07fa20b39117fb4bfb746882631b7780b?s=96&d=mm&r=g","caption":"Antonio Carlos Gaio"},"sameAs":["http:\/\/www.jornaldugaio.com.br","https:\/\/www.facebook.com\/antoniocarlos.gaio"],"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/acgaio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4883"}],"version-history":[{"count":0,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4883\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}