﻿{"id":5708,"date":"2015-04-02T00:00:02","date_gmt":"2015-04-02T16:20:49","guid":{"rendered":""},"modified":"2015-04-02T00:00:02","modified_gmt":"2015-04-02T16:20:49","slug":"a-seta","status":"publish","type":"post","link":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/","title":{"rendered":"A SETA"},"content":{"rendered":"<div class=\"fsc_text\"><div>tua seta indiscreta<\/div>\n<div>n\u00e3o me acerta<\/div>\n<div>mas me penetra<\/div>\n<div>de uma maneira<\/div>\n<div>que por mais<\/div>\n<div>que eu queira<\/div>\n<div>disfar\u00e7ar<\/div>\n<div>l\u00e1 est\u00e1 o sangue<\/div>\n<div>a transbordar<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>tua seta indiscreta n\u00e3o me acerta mas me penetra de uma maneira que por mais que eu queira disfar\u00e7ar l\u00e1 est\u00e1 o sangue a transbordar<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-5708","post","type-post","status-publish","format-standard","hentry","category-tudo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A SETA - Jornal DuGAIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A SETA - Jornal DuGAIO\" \/>\n<meta property=\"og:description\" content=\"tua seta indiscreta n\u00e3o me acerta mas me penetra de uma maneira que por mais que eu queira disfar\u00e7ar l\u00e1 est\u00e1 o sangue a transbordar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal DuGAIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/antoniocarlos.gaio\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-02T16:20:49+00:00\" \/>\n<meta name=\"author\" content=\"Mariana Valle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Valle\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A SETA - Jornal DuGAIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/","og_locale":"pt_BR","og_type":"article","og_title":"A SETA - Jornal DuGAIO","og_description":"tua seta indiscreta n\u00e3o me acerta mas me penetra de uma maneira que por mais que eu queira disfar\u00e7ar l\u00e1 est\u00e1 o sangue a transbordar","og_url":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/","og_site_name":"Jornal DuGAIO","article_publisher":"https:\/\/www.facebook.com\/antoniocarlos.gaio","article_published_time":"2015-04-02T16:20:49+00:00","author":"Mariana Valle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Valle"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/#article","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/"},"author":{"name":"Mariana Valle","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"headline":"A SETA","datePublished":"2015-04-02T16:20:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/"},"wordCount":29,"commentCount":0,"articleSection":["Tudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/","url":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/","name":"A SETA - Jornal DuGAIO","isPartOf":{"@id":"https:\/\/www.jornaldugaio.com.br\/#website"},"datePublished":"2015-04-02T16:20:49+00:00","author":{"@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8"},"breadcrumb":{"@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jornaldugaio.com.br\/index.php\/a-seta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jornaldugaio.com.br\/"},{"@type":"ListItem","position":2,"name":"A SETA"}]},{"@type":"WebSite","@id":"https:\/\/www.jornaldugaio.com.br\/#website","url":"https:\/\/www.jornaldugaio.com.br\/","name":"Jornal DuGAIO","description":"O que est\u00e1 por detr\u00e1s da not\u00edcia em r\u00e1pidas palavras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jornaldugaio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.jornaldugaio.com.br\/#\/schema\/person\/8eed1078ab7942215981d7538f9e96c8","name":"Mariana Valle","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d61c15c6812566c89814169bfb07cc176775dd20c1321c81ccef463c95a9e086?s=96&d=mm&r=g","caption":"Mariana Valle"},"url":"https:\/\/www.jornaldugaio.com.br\/index.php\/author\/mvalle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5708"}],"version-history":[{"count":0,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5708\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornaldugaio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}